{"id":109,"date":"2003-02-03T22:33:53","date_gmt":"2003-02-03T20:33:53","guid":{"rendered":"\/\/?p="},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T23:00:00","slug":"cofani-funebri","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/","title":{"rendered":"cofani funebri"},"content":{"rendered":"<p>E&#8217; finalmente arrivato il calendario che <br \/>\ntutti noi stavamo aspettando! <br \/>\nL&#8217;edizione 2003 del calendario dei <br \/>\n<a href=\"http:\/\/www.cofanifunebri.com\/calendario-2003.htm\" title=\"cofani funebri!\" target=\"_blank\">cofani funebri!<\/a> :D<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; finalmente arrivato il calendario che tutti noi stavamo aspettando! L&#8217;edizione 2003 del calendario dei cofani funebri! :D ciuaz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-109","post","type-post","status-publish","format-standard","hentry","category-cazzate"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>cofani funebri - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cofani funebri - Fullo\" \/>\n<meta property=\"og:description\" content=\"E&#8217; finalmente arrivato il calendario che tutti noi stavamo aspettando! L&#8217;edizione 2003 del calendario dei cofani funebri! :D ciuaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2003-02-03T20:33:53+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/03\\\/cofani-funebri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/03\\\/cofani-funebri\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"cofani funebri\",\"datePublished\":\"2003-02-03T20:33:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/03\\\/cofani-funebri\\\/\"},\"wordCount\":21,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"cazzate\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/03\\\/cofani-funebri\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/03\\\/cofani-funebri\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/03\\\/cofani-funebri\\\/\",\"name\":\"cofani funebri - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2003-02-03T20:33:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/03\\\/cofani-funebri\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/03\\\/cofani-funebri\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/03\\\/cofani-funebri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cofani funebri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cofani funebri - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/","og_locale":"en_US","og_type":"article","og_title":"cofani funebri - Fullo","og_description":"E&#8217; finalmente arrivato il calendario che tutti noi stavamo aspettando! L&#8217;edizione 2003 del calendario dei cofani funebri! :D ciuaz","og_url":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/","og_site_name":"Fullo","article_published_time":"2003-02-03T20:33:53+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"cofani funebri","datePublished":"2003-02-03T20:33:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/"},"wordCount":21,"commentCount":1,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["cazzate"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/","url":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/","name":"cofani funebri - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2003-02-03T20:33:53+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/03\/cofani-funebri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"cofani funebri"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-1L","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":529,"url":"https:\/\/www.fullo.net\/blog\/2003\/10\/29\/calendario-2004\/","url_meta":{"origin":109,"position":0},"title":"calendario 2004","author":"Francesco Fullone","date":"29\/10\/2003","format":false,"excerpt":"quando ho letto la notizia su manteblog non potevo crederci, i pazzi di Cofani Funebri hanno deciso di vendere il calendario 2004! A quando un blog dedicato al fantastico mondo delle bare ? ciuaz","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1054,"url":"https:\/\/www.fullo.net\/blog\/2004\/10\/12\/cofani-2005\/","url_meta":{"origin":109,"position":1},"title":"cofani 2005&#8230;","author":"Francesco Fullone","date":"12\/10\/2004","format":false,"excerpt":"finalmente \u00e8 stato pubblicato il nuovo calendario di cofani funebri.. meno male, gi\u00e0 pensavo di dovermi appendere il solito max o gq.... ciuaz","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1528,"url":"https:\/\/www.fullo.net\/blog\/2005\/07\/15\/quande-che\/","url_meta":{"origin":109,"position":2},"title":"Quand&#8217;\u00e8 che&#8230;","author":"Francesco Fullone","date":"15\/07\/2005","format":false,"excerpt":"vi siete mai scordati una certa festa padronale? o la data di qualche evento storico? oppure volete essere sempre aggiornati sul calendario sportivo della vostra squadra di calcio? iCalShare potrebbe essere la risposta alle vostre domande. Il sito in questione, gestito dall'autore di phpiCalendar, permette di iscriversi a centinaia di\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3767,"url":"https:\/\/www.fullo.net\/blog\/2021\/05\/24\/di-calendari-e-gestione-del-tempo\/","url_meta":{"origin":109,"position":3},"title":"Di calendari e gestione del tempo","author":"Francesco Fullone","date":"24\/05\/2021","format":false,"excerpt":"Il tema della gestione del calendario, durante le lecture riguardanti i temi di smart working o durante altre attivit\u00e0, emerge spesso. Ognuno ha la sua ricetta magica che funziona, pi\u00f9 o meno per la sua specifica esigenza, ma sempre incompleta sotto qualche aspetto. Lungi da me dall'annunciare la soluzione definitiva\u00ae\u2026","rel":"","context":"In &quot;advisoring&quot;","block_context":{"text":"advisoring","link":"https:\/\/www.fullo.net\/blog\/category\/entrepreneurship\/advisoring\/"},"img":{"alt_text":"calendar","src":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/31837798342_534125d025_b.jpg?fit=900%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/31837798342_534125d025_b.jpg?fit=900%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/31837798342_534125d025_b.jpg?fit=900%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/31837798342_534125d025_b.jpg?fit=900%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":461,"url":"https:\/\/www.fullo.net\/blog\/2003\/09\/15\/movable\/","url_meta":{"origin":109,"position":4},"title":"movable","author":"Francesco Fullone","date":"15\/09\/2003","format":false,"excerpt":"qualche modo alternativo di usare il calendario di movable type. ciuaz","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":689,"url":"https:\/\/www.fullo.net\/blog\/2004\/01\/29\/sempre-outlook\/","url_meta":{"origin":109,"position":5},"title":"sempre outlook","author":"Francesco Fullone","date":"29\/01\/2004","format":false,"excerpt":"dopo aver felicemente fatto convivere outlook xp con un server Domino (sfruttandone tra l'altro la rubrica ed il calendario), sto cercando qualche utility per personalizzare la pagina di Outlook:oggi affinch\u00e8 mi carichi anche il calendario appuntamenti del succitato Domino. Durante la ricerca mi sono imbattuto in alcuni interessanti siti su\u2026","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=109"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/109\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}