{"id":126,"date":"2003-02-17T20:47:02","date_gmt":"2003-02-17T18:47:02","guid":{"rendered":"\/\/?p="},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T23:00:00","slug":"voglio-partire","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/","title":{"rendered":"voglio partire"},"content":{"rendered":"<p>Ho il bisogno fisico di partire.<\/p>\n<p>cambiare aria per qualche giorno, emigrare, scomparire, macinare km, muovermi.<br \/>\nnon per sfuggire allo strozzino di turno o altro, \u00e8 proprio una necessit\u00e0 come<br \/>\nrespirare o mangiare.<\/p>\n<p>rivoglio il mio Transporter T3, non che non mi piaccia la Punto&#8230; <br \/>\nma non \u00e8 la stessa cosa!!! <br \/>\nrivoglio poter partire senza meta e senza paura di non saper dove dormire, <br \/>\nrivoglio gli amici disposti a fare una follia per un week-end senza sentirmi dire che <i>il lavoro<\/i>, <i>la morosa<\/i>, <i>gli impegni<\/i>, <i>i soldi<\/i> (e qui mi ci metto anche io! :( )&#8230;<br \/>\nrivoglio sentire l&#8217;assoluta tranquillit\u00e0 che provavo quando non avevo la minima idea di dove fossi, come avevo fatto ad arrivarci e dove potevo andare!<br \/>\nrivoglio perdermi per le viuzze Atene, Parigi, Barcellona, Amsterdam, Copenhagen, Oslo camminando per km soltanto per vedere il monumento\/negozio\/pub\/museo successivo!<br \/>\nrivoglio prendere in giro gli abitanti di qualsiasi citt\u00e0 europea rivolgendomi loro <br \/>\nin italiano, calabrese o storpiando quello che dicono.<br \/>\nrivoglio viaggiareeeeeeeeeeeeeeeeeeeeee!!!!!<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ho il bisogno fisico di partire. cambiare aria per qualche giorno, emigrare, scomparire, macinare km, muovermi. non per sfuggire allo strozzino di turno o altro, \u00e8 proprio una necessit\u00e0 come respirare o mangiare. rivoglio il mio Transporter T3, non che non mi piaccia la Punto&#8230; ma non \u00e8 la stessa cosa!!! rivoglio poter partire senza [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-126","post","type-post","status-publish","format-standard","hentry","category-pensieri"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>voglio partire - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"voglio partire - Fullo\" \/>\n<meta property=\"og:description\" content=\"Ho il bisogno fisico di partire. cambiare aria per qualche giorno, emigrare, scomparire, macinare km, muovermi. non per sfuggire allo strozzino di turno o altro, \u00e8 proprio una necessit\u00e0 come respirare o mangiare. rivoglio il mio Transporter T3, non che non mi piaccia la Punto&#8230; ma non \u00e8 la stessa cosa!!! rivoglio poter partire senza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2003-02-17T18:47:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/FB_IMG_1515748807284.jpg?fit=1453%2C1453&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"1453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/17\\\/voglio-partire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/17\\\/voglio-partire\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"voglio partire\",\"datePublished\":\"2003-02-17T18:47:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/17\\\/voglio-partire\\\/\"},\"wordCount\":165,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"pensieri\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/17\\\/voglio-partire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/17\\\/voglio-partire\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/17\\\/voglio-partire\\\/\",\"name\":\"voglio partire - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2003-02-17T18:47:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/17\\\/voglio-partire\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/17\\\/voglio-partire\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/02\\\/17\\\/voglio-partire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"voglio partire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"voglio partire - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/","og_locale":"it_IT","og_type":"article","og_title":"voglio partire - Fullo","og_description":"Ho il bisogno fisico di partire. cambiare aria per qualche giorno, emigrare, scomparire, macinare km, muovermi. non per sfuggire allo strozzino di turno o altro, \u00e8 proprio una necessit\u00e0 come respirare o mangiare. rivoglio il mio Transporter T3, non che non mi piaccia la Punto&#8230; ma non \u00e8 la stessa cosa!!! rivoglio poter partire senza [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/","og_site_name":"Fullo","article_published_time":"2003-02-17T18:47:02+00:00","og_image":[{"width":1453,"height":1453,"url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/FB_IMG_1515748807284.jpg?fit=1453%2C1453&ssl=1","type":"image\/jpeg"}],"author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Scritto da":"Francesco Fullone","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"voglio partire","datePublished":"2003-02-17T18:47:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/"},"wordCount":165,"commentCount":3,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["pensieri"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/","url":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/","name":"voglio partire - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2003-02-17T18:47:02+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"voglio partire"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-22","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":420,"url":"https:\/\/www.fullo.net\/blog\/2003\/08\/27\/eudora-60020-beta\/","url_meta":{"origin":126,"position":0},"title":"eudora 6.0.020 beta","author":"Francesco Fullone","date":"27\/08\/2003","format":false,"excerpt":"\u00e8 stata rilasciata la nuova versione beta di Eudora, tra le novit\u00e0 \u00e8 stato rimosso il supporto antispam per la versione adware :sad: e sono stati corretti alcuni bug sul supporto IMAP. Da notare anche le nuove iconcine (blu)... che per\u00f2 mi fanno schifo!!! rivoglio le cartelline marroni! \u00e8 dalla\u2026","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":476,"url":"https:\/\/www.fullo.net\/blog\/2003\/09\/26\/transfoooorm\/","url_meta":{"origin":126,"position":1},"title":"transfoooorm!!","author":"Francesco Fullone","date":"26\/09\/2003","format":false,"excerpt":"pare che vogliano girare un film sui transformers!!!! miticoooo!!! ho sempre amato il cartone, a parte l'orribile serie robot in disguise, che trasmettono da un anno su cartoon network e, che ho trovato un p\u00f2 deludente in quanto non rispetta la continuit\u00e0 creata dagli ultimi 20 anni di episodi! RIVOGLIO\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2092,"url":"https:\/\/www.fullo.net\/blog\/2006\/10\/24\/la-bici-e-tornata-o-quasi\/","url_meta":{"origin":126,"position":2},"title":"La bici \u00e8 tornata&#8230; o quasi&#8230;","author":"Francesco Fullone","date":"24\/10\/2006","format":false,"excerpt":"Oggi pomeriggio mentre andavo a prendere Diana in stazione ho ritrovato la mia adorata bici rubatami quest'estate sotto casa. Purtroppo i ladri\/vandali nel frattempo per \"mimetizzarla\" hanno ben pensato di togliere il parafango da 5 euro che avevo applicato e ridipingerla di un osceno blu (facendo ben attenzione a prendere\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2751,"url":"https:\/\/www.fullo.net\/blog\/2010\/08\/22\/100km-con-le-mbt-ai-piedi\/","url_meta":{"origin":126,"position":3},"title":"100Km con le MBT ai piedi&#8230;","author":"Francesco Fullone","date":"22\/08\/2010","format":false,"excerpt":"Come molti di voi sapranno, seguendomi su FriendFeed o su Twitter, qualche mese fa ho comprato un paio di MBT, per la precisione le Tembea White Cap, per provare a alleviare il continuo dolore al ginocchio che mi perseguita da qualche anno. Le scarpe, che premetto non sono da trekking\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2010\/08\/IMG_0286-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1582,"url":"https:\/\/www.fullo.net\/blog\/2005\/08\/10\/rafting\/","url_meta":{"origin":126,"position":4},"title":"Rafting!","author":"Francesco Fullone","date":"10\/08\/2005","format":false,"excerpt":"Domenica ho fatto per la prima volta in vita mia rafting (per chi non sapesse cosa sia il rafting: si tratta essenzialmente di seguire con un gommone la corrente del fiume per qualche km cercando di non ammazzarsi sulle rapide) e devo dire che, nonostante la fatica fisica, mi sono\u2026","rel":"","context":"In &quot;foto&quot;","block_context":{"text":"foto","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/foto\/"},"img":{"alt_text":"rafting people!","src":"https:\/\/i0.wp.com\/photos22.flickr.com\/32913924_a30dae8de7_s.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1745,"url":"https:\/\/www.fullo.net\/blog\/2005\/11\/11\/ce-sempre-da-imparare\/","url_meta":{"origin":126,"position":5},"title":"C&#8217;\u00e8 sempre da imparare&#8230;","author":"Francesco Fullone","date":"11\/11\/2005","format":false,"excerpt":"E la lezione di oggi \u00e8: Non far partire offerte di lavoro sul tuo blog personale, solo perch\u00e8 \u00e8 il modo pi\u00f9 rapido che conosci per contattare circa 3000 persone senza sforzo, se prima il richiedente non ti da delle garanzie scritte, controfirmate e vidimante da un notaio. vabb\u00e8, mi\u2026","rel":"","context":"In &quot;lifehack&quot;","block_context":{"text":"lifehack","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/lifehack\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/126\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}