{"id":13,"date":"2002-10-21T07:37:44","date_gmt":"2002-10-21T05:37:44","guid":{"rendered":"\/\/?p="},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T23:00:00","slug":"pensiero-del-giorno","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/","title":{"rendered":"Pensiero del giorno"},"content":{"rendered":"<p>Non lasciatevi prendere dal panico!<\/p>\n<blockquote><p>Guida galattica per autostoppisti<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Non lasciatevi prendere dal panico! Guida galattica per autostoppisti<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-13","post","type-post","status-publish","format-standard","hentry","category-pensieri"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pensiero del giorno - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pensiero del giorno - Fullo\" \/>\n<meta property=\"og:description\" content=\"Non lasciatevi prendere dal panico! Guida galattica per autostoppisti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2002-10-21T05:37:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/FB_IMG_1515748807284.jpg?fit=1453%2C1453&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"1453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/21\\\/pensiero-del-giorno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/21\\\/pensiero-del-giorno\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"Pensiero del giorno\",\"datePublished\":\"2002-10-21T05:37:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/21\\\/pensiero-del-giorno\\\/\"},\"wordCount\":12,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"pensieri\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/21\\\/pensiero-del-giorno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/21\\\/pensiero-del-giorno\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/21\\\/pensiero-del-giorno\\\/\",\"name\":\"Pensiero del giorno - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2002-10-21T05:37:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/21\\\/pensiero-del-giorno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/21\\\/pensiero-del-giorno\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/21\\\/pensiero-del-giorno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pensiero del giorno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pensiero del giorno - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/","og_locale":"it_IT","og_type":"article","og_title":"Pensiero del giorno - Fullo","og_description":"Non lasciatevi prendere dal panico! Guida galattica per autostoppisti","og_url":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/","og_site_name":"Fullo","article_published_time":"2002-10-21T05:37:44+00:00","og_image":[{"width":1453,"height":1453,"url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/FB_IMG_1515748807284.jpg?fit=1453%2C1453&ssl=1","type":"image\/jpeg"}],"author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Scritto da":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"Pensiero del giorno","datePublished":"2002-10-21T05:37:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/"},"wordCount":12,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["pensieri"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/","url":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/","name":"Pensiero del giorno - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2002-10-21T05:37:44+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/21\/pensiero-del-giorno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Pensiero del giorno"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-d","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":364,"url":"https:\/\/www.fullo.net\/blog\/2003\/07\/28\/42\/","url_meta":{"origin":13,"position":0},"title":"42","author":"Francesco Fullone","date":"28\/07\/2003","format":false,"excerpt":"LA RISPOSTA SU LA VITA L'UNIVERSO E TUTTO QUANTOUna razza molto curiosa un giorno volle conoscere la madre di tutte le risposte, la risposta sulla vita l'universo e tutto quanto. Per ottenerla costru\u00ec Pensiero Profondo, il computer pi\u00f9 grande e pi\u00f9 potente dell'Universo. Gli pose la domanda e poi attese\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1970,"url":"https:\/\/www.fullo.net\/blog\/2006\/05\/25\/42-2\/","url_meta":{"origin":13,"position":1},"title":"42","author":"Francesco Fullone","date":"25\/05\/2006","format":false,"excerpt":"Come vedete dal banner qui sopra oggi \u00e8 il TowelDay, giornata commemorativa per ricordarsi di Douglas Adams, l'autore della trilogia in cinque libri chiamata Guida Galattica per Autostoppisti. Quindi che aspettate? Tirate fuori il vostro asciugamano preferito e portatevelo appresso e ricordatevi che: La Guida Galattica per gli Autostoppisti dice\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1487,"url":"https:\/\/www.fullo.net\/blog\/2005\/06\/26\/a-questa-rispondo\/","url_meta":{"origin":13,"position":2},"title":"a questa rispondo&#8230;","author":"Francesco Fullone","date":"26\/06\/2005","format":false,"excerpt":"stavolta, per non so quale motivo, rispondo ad una catena... Libri della mia biblioteca: la mia biblioteca \u00e8 il bagno, oddio.. diciamo la sala di lettura... finch\u00e8 non finisco il libro e decido di metterlo da qualche parte nel mio incasinatissimo studio (spesso per terra) o di restituirlo [ leggo\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":25,"url":"https:\/\/www.fullo.net\/blog\/2002\/10\/26\/due-nuovi-libri\/","url_meta":{"origin":13,"position":3},"title":"Due nuovi libri","author":"Francesco Fullone","date":"26\/10\/2002","format":false,"excerpt":"Sono appena usciti in libreria due nuovi libri, il primo appartenente alla collana urania\/strade blu \u00e8 nientedimeno che il romanzo postumo di Douglas Adams ed \u00e8 intitolato Il salmone del dubbio. Per chi di voi non conoscesse il mitico Adams (VERGOGNA!), posso dire di lui che \u00e8 un genio della\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1041,"url":"https:\/\/www.fullo.net\/blog\/2004\/10\/10\/lotte-galattiche\/","url_meta":{"origin":13,"position":4},"title":"lotte galattiche","author":"Francesco Fullone","date":"10\/10\/2004","format":false,"excerpt":"da buon informatico ho comprato il cofanetto di star wars e sono rimasto interdetto, come altri, da alcune scene. Sempre da buon informatico mi sono messo su google per vedere se qualche appassionato avesse stilato una lista delle modifiche, ed ecco che sam davatchi propone sulla sua homepage un interessante\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":126,"url":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/","url_meta":{"origin":13,"position":5},"title":"voglio partire","author":"Francesco Fullone","date":"17\/02\/2003","format":false,"excerpt":"Ho il bisogno fisico di partire. cambiare aria per qualche giorno, emigrare, scomparire, macinare km, muovermi. non per sfuggire allo strozzino di turno o altro, \u00e8 proprio una necessit\u00e0 come respirare o mangiare. rivoglio il mio Transporter T3, non che non mi piaccia la Punto... ma non \u00e8 la stessa\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/13\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=13"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=13"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}