{"id":1330,"date":"2005-04-02T20:23:41","date_gmt":"2005-04-02T18:23:41","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/index.php\/archives\/2005\/04\/02\/gloria-gloria-gloria\/"},"modified":"2005-04-02T20:23:41","modified_gmt":"2005-04-02T18:23:41","slug":"gloria-gloria-gloria","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/","title":{"rendered":"Gloria gloria gloria!"},"content":{"rendered":"<p>Gloria gloria gloria! <a href=\"http:\/\/www.ipnorospo.com\/index.htm\">Ipnorospo<\/a> nostro signore&#8230;<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gloria gloria gloria! Ipnorospo nostro signore&#8230; ciuaz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-1330","post","type-post","status-publish","format-standard","hentry","category-cazzate"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gloria gloria gloria! - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gloria gloria gloria! - Fullo\" \/>\n<meta property=\"og:description\" content=\"Gloria gloria gloria! Ipnorospo nostro signore&#8230; ciuaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2005-04-02T18:23:41+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/04\\\/02\\\/gloria-gloria-gloria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/04\\\/02\\\/gloria-gloria-gloria\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"Gloria gloria gloria!\",\"datePublished\":\"2005-04-02T18:23:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/04\\\/02\\\/gloria-gloria-gloria\\\/\"},\"wordCount\":10,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"cazzate\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/04\\\/02\\\/gloria-gloria-gloria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/04\\\/02\\\/gloria-gloria-gloria\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/04\\\/02\\\/gloria-gloria-gloria\\\/\",\"name\":\"Gloria gloria gloria! - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2005-04-02T18:23:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/04\\\/02\\\/gloria-gloria-gloria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/04\\\/02\\\/gloria-gloria-gloria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/04\\\/02\\\/gloria-gloria-gloria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gloria gloria gloria!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gloria gloria gloria! - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/","og_locale":"en_US","og_type":"article","og_title":"Gloria gloria gloria! - Fullo","og_description":"Gloria gloria gloria! Ipnorospo nostro signore&#8230; ciuaz","og_url":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/","og_site_name":"Fullo","article_published_time":"2005-04-02T18:23:41+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"Gloria gloria gloria!","datePublished":"2005-04-02T18:23:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/"},"wordCount":10,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["cazzate"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/","url":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/","name":"Gloria gloria gloria! - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2005-04-02T18:23:41+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2005\/04\/02\/gloria-gloria-gloria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Gloria gloria gloria!"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-ls","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":536,"url":"https:\/\/www.fullo.net\/blog\/2003\/10\/31\/la-sagra-delle-cazzate\/","url_meta":{"origin":1330,"position":0},"title":"la sagra delle cazzate","author":"Francesco Fullone","date":"31\/10\/2003","format":false,"excerpt":"ho trovato sul blog di Matteo Baccan una serie impressionante di minchiate... eccone un breve e selezionato riassunto: - le divertentissime avventure di boombastick - il ....tore per l'uomo che non deve chiedere mai! - il generatore di cookbook - xiaoxiao get beer ciuaz","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1859,"url":"https:\/\/www.fullo.net\/blog\/2006\/02\/01\/infettato\/","url_meta":{"origin":1330,"position":1},"title":"Infettato&#8230;","author":"Francesco Fullone","date":"01\/02\/2006","format":false,"excerpt":"porkamiseria mi hanno infettato il blog! ciuaz","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"Blog.Worm","src":"https:\/\/i0.wp.com\/www.moox.nl\/blogworm\/virus.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2523,"url":"https:\/\/www.fullo.net\/blog\/2008\/12\/17\/hey-lo-sai-che\/","url_meta":{"origin":1330,"position":2},"title":"hey&#8230; lo sai che&#8230;","author":"Francesco Fullone","date":"17\/12\/2008","format":false,"excerpt":"ciuaz","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"culez","src":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/culez.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1861,"url":"https:\/\/www.fullo.net\/blog\/2006\/02\/02\/10-cazzate-da-attaccare-ad-una-porta-usb\/","url_meta":{"origin":1330,"position":3},"title":"10 cazzate da attaccare ad una porta USB","author":"Francesco Fullone","date":"02\/02\/2006","format":false,"excerpt":"Fosfor Gadget pubblica la classifica delle 10 peggio minchiate da attaccare ad una porta USB, siccome a breve \u00e8 il mio compleanno e so che smaniate dalla voglia di farmi un regalo vi suggerisco le inutility in posizione 2,5,6 e 9 anche se in realt\u00e0 [ad esclusioni della prima ;)\u2026","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1428,"url":"https:\/\/www.fullo.net\/blog\/2005\/06\/03\/gatling\/","url_meta":{"origin":1330,"position":4},"title":"gatling","author":"Francesco Fullone","date":"03\/06\/2005","format":false,"excerpt":"per i fans di Django ecco a voi la prima gatling gun in legno che spara elastici :) ciuaz","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2078,"url":"https:\/\/www.fullo.net\/blog\/2006\/10\/13\/totem-il-gioco-stupido-del-venerdi\/","url_meta":{"origin":1330,"position":5},"title":"Totem, il gioco stupido del venerd\u00ec&#8230;","author":"Francesco Fullone","date":"13\/10\/2006","format":false,"excerpt":"ciuaz","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1330"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1330\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}