{"id":1375,"date":"2005-05-05T14:57:59","date_gmt":"2005-05-05T12:57:59","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/index.php\/archives\/2005\/05\/05\/feedwordpress\/"},"modified":"2005-05-05T14:59:05","modified_gmt":"2005-05-05T12:59:05","slug":"feedwordpress","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/","title":{"rendered":"FeedWordPress"},"content":{"rendered":"<p>Finalmente! Abbandono lo script che stavo realizzando durante i momenti morti delle mie giornate lavorative (e quindi MAI) e passo a qualcosa di preconfezionato per il <a href=\"http:\/\/blog.grusp.it\">blog del grusp<\/a>! :)<\/p>\n<blockquote><p><a href=\"http:\/\/projects.radgeek.com\/feedwordpress\/\">FeedWordPress<\/a> is an Atom\/RSS aggregator for WordPress. It syndicates content from newsfeeds that you select into your WordPress blog; if you syndicate several newsfeeds then you can WordPress\u2019s posts database and templating engine as the back-end of an aggregation (\u201dplanet\u201d) website. I originally developed it because I needed a more flexible replacement for Planet to use at Feminist Blogs.<\/p><\/blockquote>\n<p>via <a href=\"http:\/\/www.aronchi.org\/blog\/index.php\/archives\/2005\/05\/04\/digitaldivide-u2026e-wordpress-diventa-un-aggregatore\/\">il fiore del cactus<\/a>.<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalmente! Abbandono lo script che stavo realizzando durante i momenti morti delle mie giornate lavorative (e quindi MAI) e passo a qualcosa di preconfezionato per il blog del grusp! :) FeedWordPress is an Atom\/RSS aggregator for WordPress. It syndicates content from newsfeeds that you select into your WordPress blog; if you syndicate several newsfeeds then [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-1375","post","type-post","status-publish","format-standard","hentry","category-php"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FeedWordPress - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FeedWordPress - Fullo\" \/>\n<meta property=\"og:description\" content=\"Finalmente! Abbandono lo script che stavo realizzando durante i momenti morti delle mie giornate lavorative (e quindi MAI) e passo a qualcosa di preconfezionato per il blog del grusp! :) FeedWordPress is an Atom\/RSS aggregator for WordPress. It syndicates content from newsfeeds that you select into your WordPress blog; if you syndicate several newsfeeds then [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2005-05-05T12:57:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2005-05-05T12:59:05+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/05\\\/05\\\/feedwordpress\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/05\\\/05\\\/feedwordpress\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"FeedWordPress\",\"datePublished\":\"2005-05-05T12:57:59+00:00\",\"dateModified\":\"2005-05-05T12:59:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/05\\\/05\\\/feedwordpress\\\/\"},\"wordCount\":97,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"php\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/05\\\/05\\\/feedwordpress\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/05\\\/05\\\/feedwordpress\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/05\\\/05\\\/feedwordpress\\\/\",\"name\":\"FeedWordPress - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2005-05-05T12:57:59+00:00\",\"dateModified\":\"2005-05-05T12:59:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/05\\\/05\\\/feedwordpress\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/05\\\/05\\\/feedwordpress\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/05\\\/05\\\/feedwordpress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FeedWordPress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FeedWordPress - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/","og_locale":"en_US","og_type":"article","og_title":"FeedWordPress - Fullo","og_description":"Finalmente! Abbandono lo script che stavo realizzando durante i momenti morti delle mie giornate lavorative (e quindi MAI) e passo a qualcosa di preconfezionato per il blog del grusp! :) FeedWordPress is an Atom\/RSS aggregator for WordPress. It syndicates content from newsfeeds that you select into your WordPress blog; if you syndicate several newsfeeds then [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/","og_site_name":"Fullo","article_published_time":"2005-05-05T12:57:59+00:00","article_modified_time":"2005-05-05T12:59:05+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"FeedWordPress","datePublished":"2005-05-05T12:57:59+00:00","dateModified":"2005-05-05T12:59:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/"},"wordCount":97,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["php"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/","url":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/","name":"FeedWordPress - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2005-05-05T12:57:59+00:00","dateModified":"2005-05-05T12:59:05+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2005\/05\/05\/feedwordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"FeedWordPress"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-mb","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1755,"url":"https:\/\/www.fullo.net\/blog\/2005\/11\/15\/aggiornato-feedwordpress\/","url_meta":{"origin":1375,"position":0},"title":"Aggiornato FeedWordPress","author":"Francesco Fullone","date":"15\/11\/2005","format":false,"excerpt":"Aggiornato FeedWordpress il plugin per WordPress che permette di aggregare news provenienti da altre fonti sul proprio blog. Le novit\u00e0 sono tantissime e altrettanti sono i bugfix. Un esempio del suo funzionamento \u00e8 il blog aggregatore del GrUSP che cerca di emulare un planet-php all'italiana. ciauz","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2194,"url":"https:\/\/www.fullo.net\/blog\/2007\/01\/17\/php-italian-aggregator-e-php-6\/","url_meta":{"origin":1375,"position":1},"title":"PHP Italian aggregator e PHP 6","author":"Francesco Fullone","date":"17\/01\/2007","format":false,"excerpt":"Aggregatori ed aggregati Siccome il plugin per la creazione degli aggregatori con wordpress non funziona pi\u00f9 un granch\u00e8 bene con la versione 2.x ho pensato di provare due possibili alternative per il planet-php italiano. La prima consiste nell'utilizzo del nuovo fiammante account da network mananger, che mi \u00e8 stato offerto\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1987,"url":"https:\/\/www.fullo.net\/blog\/2006\/06\/20\/un-nuovo-php-ista-online\/","url_meta":{"origin":1375,"position":2},"title":"Un nuovo php-ista online","author":"Francesco Fullone","date":"20\/06\/2006","format":false,"excerpt":"L'azione di persuasione fatta da me e koolinus durante la cena del phpDay ha decisamente dato dei buoni frutti! Adesso anche Gaetano ha finalmente messo su il suo blog! Adesso bisogna iniziarle a martellare per fargli fare qualche post in italiano, cos\u00ec da aggregarlo sul simil planet-php italiano del GrUSP.\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2420,"url":"https:\/\/www.fullo.net\/blog\/2008\/04\/10\/shell-history-meme\/","url_meta":{"origin":1375,"position":3},"title":"Shell History meme","author":"Francesco Fullone","date":"10\/04\/2008","format":false,"excerpt":"Lo Shell History Meme Sta girando da qualche giorno sui vari planet che leggo con piacere, ed e' uno di quei pochi meme talmente geek che non posso evitare di partecipare.. basta scrivere in shell il seguente comando: history | awk '{a[$2]++ } END{for(i in a){print a[i] \" \" i}}'|sort\u2026","rel":"","context":"In &quot;altri linguaggi&quot;","block_context":{"text":"altri linguaggi","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/altri-linguaggi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1386,"url":"https:\/\/www.fullo.net\/blog\/2005\/05\/10\/hai-un-blog-sul-php\/","url_meta":{"origin":1375,"position":4},"title":"Hai un blog sul php?","author":"Francesco Fullone","date":"10\/05\/2005","format":false,"excerpt":"CONTATTAMI! Tramite il blog-grusp verr\u00e0 realizzato il primo planet-php italiano. ciuaz","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1852,"url":"https:\/\/www.fullo.net\/blog\/2006\/01\/18\/tooltip-design-pattern-ed-altro\/","url_meta":{"origin":1375,"position":5},"title":"Tooltip, design pattern ed altro","author":"Francesco Fullone","date":"18\/01\/2006","format":false,"excerpt":"Post riassunto delle chicche tecnologiche scovate negli ultimi giorni: Tooltip.js: un piccolo javascript che si affianca a scriptacoulus per la gestione di tooltip animati e non Design Pattern in Dynamic Programming: slide che spiegano il paradigma del design pattern. Sono state scritte quasi 10 anni fa ma rimangono attualissime php4it\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1375"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1375\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}