{"id":1506,"date":"2005-07-07T11:51:32","date_gmt":"2005-07-07T09:51:32","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/index.php\/archives\/2005\/07\/07\/ruby-on-rails-013\/"},"modified":"2005-07-07T11:51:32","modified_gmt":"2005-07-07T09:51:32","slug":"ruby-on-rails-013","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/","title":{"rendered":"ruby on rails 0.13"},"content":{"rendered":"<p>E&#8217; uscita la nuova versione del framework scritto in ruby che sfrutta in maniera massiva le tecniche ajax. Questa versione di ruby-on-rails a <a href=\"http:\/\/weblog.rubyonrails.com\/archives\/2005\/07\/06\/rails-013-225-featuresfixes-in-75-days\/\">detta degli autori<\/a> implementa pi\u00f9 di 225 nuove features (molte delle quali derivate dall&#8217;utilizzo di <a href=\"http:\/\/script.aculo.us\/demos\/\">script.acul.us<\/a>)<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; uscita la nuova versione del framework scritto in ruby che sfrutta in maniera massiva le tecniche ajax. Questa versione di ruby-on-rails a detta degli autori implementa pi\u00f9 di 225 nuove features (molte delle quali derivate dall&#8217;utilizzo di script.acul.us) ciuaz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14,10],"tags":[2252,342,343],"class_list":["post-1506","post","type-post","status-publish","format-standard","hentry","category-ajax","category-altri-linguaggi","tag-ajax","tag-ruby","tag-rubyonrails"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ruby on rails 0.13 - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ruby on rails 0.13 - Fullo\" \/>\n<meta property=\"og:description\" content=\"E&#8217; uscita la nuova versione del framework scritto in ruby che sfrutta in maniera massiva le tecniche ajax. Questa versione di ruby-on-rails a detta degli autori implementa pi\u00f9 di 225 nuove features (molte delle quali derivate dall&#8217;utilizzo di script.acul.us) ciuaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-07T09:51:32+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/07\\\/ruby-on-rails-013\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/07\\\/ruby-on-rails-013\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"ruby on rails 0.13\",\"datePublished\":\"2005-07-07T09:51:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/07\\\/ruby-on-rails-013\\\/\"},\"wordCount\":45,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"ajax\",\"ruby\",\"rubyonrails\"],\"articleSection\":[\"ajax\",\"altri linguaggi\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/07\\\/ruby-on-rails-013\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/07\\\/ruby-on-rails-013\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/07\\\/ruby-on-rails-013\\\/\",\"name\":\"ruby on rails 0.13 - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2005-07-07T09:51:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/07\\\/ruby-on-rails-013\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/07\\\/ruby-on-rails-013\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/07\\\/ruby-on-rails-013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ruby on rails 0.13\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ruby on rails 0.13 - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/","og_locale":"en_US","og_type":"article","og_title":"ruby on rails 0.13 - Fullo","og_description":"E&#8217; uscita la nuova versione del framework scritto in ruby che sfrutta in maniera massiva le tecniche ajax. Questa versione di ruby-on-rails a detta degli autori implementa pi\u00f9 di 225 nuove features (molte delle quali derivate dall&#8217;utilizzo di script.acul.us) ciuaz","og_url":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/","og_site_name":"Fullo","article_published_time":"2005-07-07T09:51:32+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"ruby on rails 0.13","datePublished":"2005-07-07T09:51:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/"},"wordCount":45,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["ajax","ruby","rubyonrails"],"articleSection":["ajax","altri linguaggi"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/","url":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/","name":"ruby on rails 0.13 - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2005-07-07T09:51:32+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"ruby on rails 0.13"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-oi","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1838,"url":"https:\/\/www.fullo.net\/blog\/2006\/01\/10\/developer-notes-per-prototypejs\/","url_meta":{"origin":1506,"position":0},"title":"Developer notes per prototype.js","author":"Francesco Fullone","date":"10\/01\/2006","format":false,"excerpt":"Prototype \u00e8 una libreria js per creare animazioni, usare ajax e fare altre mille cosette. Ed \u00e8 alla base di molte delle funzionalit\u00e0 di Ruby on Rails. Grande difetto di questa libreria \u00e8 che, a parte qualche scarno esempio, non esiste un manuale decente e l'unico modo per conoscere il\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1874,"url":"https:\/\/www.fullo.net\/blog\/2006\/02\/16\/javascript-ruby-e-php\/","url_meta":{"origin":1506,"position":1},"title":"Javascript, Ruby e PHP","author":"Francesco Fullone","date":"16\/02\/2006","format":false,"excerpt":"Oggi mi sento pigro e quindi pubblico una sfilza di link tecnologici senza commentarli pi\u00f9 di tanto... Mastering Ajax \u00e8 arrivato al terzo appuntamento, il tutorial scritto su IBM DevelopWorks sulle tecniche Ajax sta raggiungendo alcuni spunti interessanti e poco banali e questa volta si parla di header, server requests\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2196,"url":"https:\/\/www.fullo.net\/blog\/2007\/01\/19\/prototype-15\/","url_meta":{"origin":1506,"position":2},"title":"Prototype 1.5","author":"Francesco Fullone","date":"19\/01\/2007","format":false,"excerpt":"Finalmente Prototype ha un sito decente e della documentazione decente, il tutto \u00e8 stato fatto per lanciare la nuova versione 1.5 rilasciata insieme al nuovo Ruby on Rails 1.2. Le novit\u00e0 sono troppe e siccome \u00e8 venerd\u00ec e mi sento pigro ecco il changelog.. leggetevelo! :P ciuaz","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1737,"url":"https:\/\/www.fullo.net\/blog\/2005\/11\/08\/ajax-news-3\/","url_meta":{"origin":1506,"position":3},"title":"Ajax news","author":"Francesco Fullone","date":"08\/11\/2005","format":false,"excerpt":"Da qualche settimana non pubblico nessun link su ajax, ecco qui una lista per risolvere il problema: AFlax \u00e8 uno script js per interfacciarsi direttamente a flash, onestamente non ho ancora studiato come fa ma dai demo sembra interessante.... [via Ajaxian] Napolux mi comunica che ha realizzato un piccolo tutorial,\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2226,"url":"https:\/\/www.fullo.net\/blog\/2007\/03\/01\/symfony-10-ed-ajax\/","url_meta":{"origin":1506,"position":4},"title":"Symfony 1.0 ed Ajax","author":"Francesco Fullone","date":"01\/03\/2007","format":false,"excerpt":"E' finalmente stata rilasciata la prima versione stabile di Symfony 1.0. Noto application framework per PHP 5 di cui ho gi\u00e0 discusso pi\u00f9 volte e che ho iniziato ad usare attivamente nell'ultimo mese e mezzo grazie ad un lavoro con Ciccio (mio guru sull'argomento). Tra le magie di questa versione,\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1531,"url":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/on-rails\/","url_meta":{"origin":1506,"position":5},"title":"*-on-rails","author":"Francesco Fullone","date":"18\/07\/2005","format":false,"excerpt":"su OSNews c'\u00e8 una interessante discussione sui framework simili a Ruby on Rails ma scritti per altri linguaggi. ciuaz","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1506"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1506\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}