{"id":1526,"date":"2005-07-14T23:05:00","date_gmt":"2005-07-14T21:05:00","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/?p=1526"},"modified":"2005-07-14T23:30:34","modified_gmt":"2005-07-14T21:30:34","slug":"come-ti-scarico-le-foto-senza-navigarti-sul-sito","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/","title":{"rendered":"Come ti scarico le foto senza navigarti sul sito&#8230;"},"content":{"rendered":"<p>ovvero come scarico tutte le immagini che hanno nomi sequenziali senza usare wget sul mio pc! ;)<\/p>\n<p>Spesso si \u00e8 nella situazione di doversi scaricare molte immagini da un sito, come ad esempio gli ultimi screenshot di qualche esotica distribuzione linux da <a href=\"http:\/\/shots.osdir.com\/\">osDir<\/a> o le foto di qualche <em>esotica<\/em>, e non si ha a disposizione wget e linux. Come fare quindi? Andare in ogni singola pagina e salvare l&#8217;immagine pare un p\u00f2 eccessivo, ed ecco quindi che viene in nostro aiuto <a href=\"http:\/\/fusker.lewww.com\/\">Fusker<\/a>.<\/p>\n<p>Fusker \u00e8 l&#8217;ennesima web application, il cui nome <a href=\"http:\/\/en.wikipedia.org\/wiki\/Fusker#Etymology\">deriva dalla traduzione del termine imbroglione\/sfruttatore in danese<\/a>, che permette, dandole in pasto un&#8217;url e gli opportuni parametri, di scaricare qualsiasi sequenza di immagine.<\/p>\n<p><!--more--><br \/>\nFacciamo un esempio, prendiamo una <a href=\"http:\/\/shots.osdir.com\/slideshows\/slideshow.php?release=280&#038;slide=7&#038;title=gnome+2.10.0+gnomelivecd+screenshots\">distribuzione a caso<\/a> e guardiamo come si chiamano le immagini, scopriremo che hanno tutte un nome sequenziale come <\/p>\n<p><code><a href=\"http:\/\/shots.osdir.com\/slideshows\/280_or\/8.png\">http:\/\/shots.osdir.com\/slideshows\/280_or\/8.png<\/a> <\/code><\/p>\n<p>e sono salvate all&#8217;interno della stessa directory. A questo punto per scaricarsi tutti gli screenshot baster\u00e0 indicare a Fusker il path e la sequenza da analizzare, cio\u00e8 qualcosa del tipo:<\/p>\n<p><code>http:\/\/shots.osdir.com\/slideshows\/280_or\/[1-84].png<\/code><\/p>\n<p>e se anche le directory fossero sequenziali? Beh in questo caso potremmo indicare una sequenza del genere<\/p>\n<p><code>http:\/\/shots.osdir.com\/slideshows\/[1-280]_or\/[1-100].png<\/code><\/p>\n<p>iniziate a capire? Beh adesso lasciate perdere l&#8217;informatica e dedicatevi a qualcosa di <em><a href=\"http:\/\/fusker.lewww.com\/index.php?lid=790421&#038;offset=180&#038;special=preview\">pi\u00f9 salutare<\/a><\/em> ;)<\/p>\n<p>[via <a href=\"http:\/\/pornhacks.blogspot.com\/2005\/07\/fusking-we-will-go_13.html\">PornHacks<\/a>]<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ovvero come scarico tutte le immagini che hanno nomi sequenziali senza usare wget sul mio pc! ;) Spesso si \u00e8 nella situazione di doversi scaricare molte immagini da un sito, come ad esempio gli ultimi screenshot di qualche esotica distribuzione linux da osDir o le foto di qualche esotica, e non si ha a disposizione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,5],"tags":[373,374,375],"class_list":["post-1526","post","type-post","status-publish","format-standard","hentry","category-cazzate","category-tecnologia","tag-fusking","tag-image-grabbing","tag-pron"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come ti scarico le foto senza navigarti sul sito... - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come ti scarico le foto senza navigarti sul sito... - Fullo\" \/>\n<meta property=\"og:description\" content=\"ovvero come scarico tutte le immagini che hanno nomi sequenziali senza usare wget sul mio pc! ;) Spesso si \u00e8 nella situazione di doversi scaricare molte immagini da un sito, come ad esempio gli ultimi screenshot di qualche esotica distribuzione linux da osDir o le foto di qualche esotica, e non si ha a disposizione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-14T21:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2005-07-14T21:30:34+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/14\\\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/14\\\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"Come ti scarico le foto senza navigarti sul sito&#8230;\",\"datePublished\":\"2005-07-14T21:05:00+00:00\",\"dateModified\":\"2005-07-14T21:30:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/14\\\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\\\/\"},\"wordCount\":214,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"fusking\",\"image grabbing\",\"pron\"],\"articleSection\":[\"cazzate\",\"tecnologia\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/14\\\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/14\\\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/14\\\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\\\/\",\"name\":\"Come ti scarico le foto senza navigarti sul sito... - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2005-07-14T21:05:00+00:00\",\"dateModified\":\"2005-07-14T21:30:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/14\\\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/14\\\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/14\\\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come ti scarico le foto senza navigarti sul sito&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come ti scarico le foto senza navigarti sul sito... - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/","og_locale":"en_US","og_type":"article","og_title":"Come ti scarico le foto senza navigarti sul sito... - Fullo","og_description":"ovvero come scarico tutte le immagini che hanno nomi sequenziali senza usare wget sul mio pc! ;) Spesso si \u00e8 nella situazione di doversi scaricare molte immagini da un sito, come ad esempio gli ultimi screenshot di qualche esotica distribuzione linux da osDir o le foto di qualche esotica, e non si ha a disposizione [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/","og_site_name":"Fullo","article_published_time":"2005-07-14T21:05:00+00:00","article_modified_time":"2005-07-14T21:30:34+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"Come ti scarico le foto senza navigarti sul sito&#8230;","datePublished":"2005-07-14T21:05:00+00:00","dateModified":"2005-07-14T21:30:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/"},"wordCount":214,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["fusking","image grabbing","pron"],"articleSection":["cazzate","tecnologia"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/","url":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/","name":"Come ti scarico le foto senza navigarti sul sito... - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2005-07-14T21:05:00+00:00","dateModified":"2005-07-14T21:30:34+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/14\/come-ti-scarico-le-foto-senza-navigarti-sul-sito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Come ti scarico le foto senza navigarti sul sito&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-oC","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1724,"url":"https:\/\/www.fullo.net\/blog\/2005\/11\/03\/breezy-e-creative-webcam-live\/","url_meta":{"origin":1526,"position":0},"title":"Breezy e Creative WebCam Live!","author":"Francesco Fullone","date":"03\/11\/2005","format":false,"excerpt":"Ho comprato dopo qualche ricerca la Creative Live! Webcam conscio che \u00e8 una delle poche compatibili con linux, ed il mio disappunto, quando ho inserito la presa usb nel pc, nel vedere che il sistema si bloccava \u00e8 stato abbastanza elevato. Per fortuna ho trovato subito sul forum di ubuntu\u2026","rel":"","context":"In &quot;linux&quot;","block_context":{"text":"linux","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/linux\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1395,"url":"https:\/\/www.fullo.net\/blog\/2005\/05\/13\/where-is-my-wife\/","url_meta":{"origin":1526,"position":1},"title":"where is my wife?","author":"Francesco Fullone","date":"13\/05\/2005","format":false,"excerpt":"Google ha recentemente comprato Dodgeball un social software per cellulari che permetti di comunicare a tutti i propri amici presenti entro qualche cella GSM dove ci si trova. La cosa di per se non \u00e8 una novit\u00e0 sia perch\u00e8 Google \u00e8 impegnata da tempo nell'acquisto di aziende\/prodotti per il social\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1703,"url":"https:\/\/www.fullo.net\/blog\/2005\/10\/20\/links-sparsi\/","url_meta":{"origin":1526,"position":2},"title":"links sparsi","author":"Francesco Fullone","date":"20\/10\/2005","format":false,"excerpt":"E' stata (finalmente) rilasciata la versione 2.0 di OpenOffice.org nessuna novit\u00e0 dalle ultime 3 rc se non qualche bugfix. Ubuntu diventa anche server, Canonical ha infatti rilasciato una versione specifica per il mondo server dell'ultima nata Breezy. Firefox raggiunge i 100 milioni di download, complimenti! :) VmWare ha rilasciato VmPlayer,\u2026","rel":"","context":"In &quot;linux&quot;","block_context":{"text":"linux","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/linux\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2279,"url":"https:\/\/www.fullo.net\/blog\/2007\/06\/03\/e-arrivato-ln95-prime-impressioni\/","url_meta":{"origin":1526,"position":3},"title":"E&#8217; arrivato l&#8217;N95, prime impressioni&#8230;","author":"Francesco Fullone","date":"03\/06\/2007","format":false,"excerpt":"E poi dicono che prostrarsi ai piedi delle aziende non serva a nulla... ho ottenuto grazie a Zeno, insieme ad una cricca di blogger pi\u00f9 o meno nota, un N95 fiammante da provare\/testare per un mesetto. Onestamente avrei preferito averlo in omaggio ad vitam, ma per ora non mi lamento\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"Unpaking\/5 - l'agognato N95","src":"https:\/\/i0.wp.com\/farm1.static.flickr.com\/247\/528576766_223f58ed40_m.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1179,"url":"https:\/\/www.fullo.net\/blog\/2004\/12\/29\/extreme-bugmenot\/","url_meta":{"origin":1526,"position":4},"title":"extreme bugmenot!","author":"Francesco Fullone","date":"29\/12\/2004","format":false,"excerpt":"bugmenot \u00e8 un sito che da la possibilit\u00e0 di salvare degli username\/password da condividere in rete, \u00e8 molto utile ad esempio per non doversi registrare come utente nei siti che lo richiedono per scaricare qualcosa o per accedere a qualche servizio. Fin qui nulla di nuovo, ma quello che non\u2026","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1646,"url":"https:\/\/www.fullo.net\/blog\/2005\/09\/14\/gallery-20\/","url_meta":{"origin":1526,"position":5},"title":"Gallery 2.0","author":"Francesco Fullone","date":"14\/09\/2005","format":false,"excerpt":"Finalmente, dopo quasi due anni di sviluppo, \u00e8 stata rilasciata la versione 2.0 di Gallery, noto script in php per la gestione di gallerie di immagini. Questa versione dell'applicativo, che \u00e8 praticamente una riscrittura da zero del precedente, ha una gestione dei temi e dei template molto potente e basata\u2026","rel":"","context":"In &quot;open source&quot;","block_context":{"text":"open source","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/open-source\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1526"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1526\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}