{"id":1532,"date":"2005-07-18T02:52:19","date_gmt":"2005-07-18T00:52:19","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/index.php\/archives\/2005\/07\/18\/dove-voglio-andare\/"},"modified":"2005-07-18T02:52:19","modified_gmt":"2005-07-18T00:52:19","slug":"dove-voglio-andare","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/","title":{"rendered":"dove voglio andare?"},"content":{"rendered":"<style type=\"text\/css\"> div#places-map-header { font-weight: bold; font-size: 14px; } <\/style>\n<p> <script language=\"javascript\" type=\"text\/javascript\" src=\"http:\/\/www.43places.com\/people\/map\/fullo?width=200&#038;content=both\"><\/script><\/p>\n<p>lista dei posti dove sono stato e dove voglio andare (in continuo aggiornamento) powered by <a href=\"http:\/\/www.43places.com\/\">43 places<\/a>!<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>lista dei posti dove sono stato e dove voglio andare (in continuo aggiornamento) powered by 43 places! ciuaz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[388,308,75],"class_list":["post-1532","post","type-post","status-publish","format-standard","hentry","category-di-tutto-un-po","tag-388","tag-flickr","tag-viaggi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>dove voglio andare? - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dove voglio andare? - Fullo\" \/>\n<meta property=\"og:description\" content=\"lista dei posti dove sono stato e dove voglio andare (in continuo aggiornamento) powered by 43 places! ciuaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-18T00:52:19+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/18\\\/dove-voglio-andare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/18\\\/dove-voglio-andare\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"dove voglio andare?\",\"datePublished\":\"2005-07-18T00:52:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/18\\\/dove-voglio-andare\\\/\"},\"wordCount\":20,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"43\",\"flickr\",\"viaggi\"],\"articleSection\":[\"di tutto un po'\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/18\\\/dove-voglio-andare\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/18\\\/dove-voglio-andare\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/18\\\/dove-voglio-andare\\\/\",\"name\":\"dove voglio andare? - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2005-07-18T00:52:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/18\\\/dove-voglio-andare\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/18\\\/dove-voglio-andare\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/07\\\/18\\\/dove-voglio-andare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"dove voglio andare?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"dove voglio andare? - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/","og_locale":"en_US","og_type":"article","og_title":"dove voglio andare? - Fullo","og_description":"lista dei posti dove sono stato e dove voglio andare (in continuo aggiornamento) powered by 43 places! ciuaz","og_url":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/","og_site_name":"Fullo","article_published_time":"2005-07-18T00:52:19+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"dove voglio andare?","datePublished":"2005-07-18T00:52:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/"},"wordCount":20,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["43","flickr","viaggi"],"articleSection":["di tutto un po'"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/","url":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/","name":"dove voglio andare? - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2005-07-18T00:52:19+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2005\/07\/18\/dove-voglio-andare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"dove voglio andare?"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-oI","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":126,"url":"https:\/\/www.fullo.net\/blog\/2003\/02\/17\/voglio-partire\/","url_meta":{"origin":1532,"position":0},"title":"voglio partire","author":"Francesco Fullone","date":"17\/02\/2003","format":false,"excerpt":"Ho il bisogno fisico di partire. cambiare aria per qualche giorno, emigrare, scomparire, macinare km, muovermi. non per sfuggire allo strozzino di turno o altro, \u00e8 proprio una necessit\u00e0 come respirare o mangiare. rivoglio il mio Transporter T3, non che non mi piaccia la Punto... ma non \u00e8 la stessa\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":231,"url":"https:\/\/www.fullo.net\/blog\/2003\/05\/04\/il-portatile\/","url_meta":{"origin":1532,"position":1},"title":"il portatile","author":"Francesco Fullone","date":"04\/05\/2003","format":false,"excerpt":"breve promemoria dei posti dove voglio usare il portatile (# = l'ho usato):- in bagno # - in macchina # - in cucina mentre mangio # - in giardino # - a letto # - al bar # - in treno - al parco - in spiaggia - nella vasca\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1733,"url":"https:\/\/www.fullo.net\/blog\/2005\/11\/07\/italian-ia-summit\/","url_meta":{"origin":1532,"position":2},"title":"Italian IA Summit","author":"Francesco Fullone","date":"07\/11\/2005","format":false,"excerpt":"Scopro, grazie ad Alberto, che il 26 Febbraio ci sar\u00e0 il primo summit italiano di information architecture. Per fortuna ho gi\u00e0 trovato dove andare a dormire.. vero dott. Mucignat? :P ciuaz","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2440,"url":"https:\/\/www.fullo.net\/blog\/2008\/07\/15\/ma-la-blogdinner-se-fa\/","url_meta":{"origin":1532,"position":3},"title":"Ma la blogDinner? Se fa?!","author":"Francesco Fullone","date":"15\/07\/2008","format":false,"excerpt":"Ok, non \u00e8 che mi sono scordato di voi mangioni \u00e8 che ho perso tempo cercando un posto dove andare a mangiare che accontentasse un po' tutti, compresa quella minoranza etnica erbivora ormai parte integrante delle blogDinner roMagnole. Pertanto ho deciso, in un momento di massima pigrizia che VENERDI 18\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":562,"url":"https:\/\/www.fullo.net\/blog\/2003\/11\/17\/sus-e-windows-2000\/","url_meta":{"origin":1532,"position":4},"title":"sus e windows 2000","author":"Francesco Fullone","date":"17\/11\/2003","format":false,"excerpt":"oggi ho imparato come modificare gli installer microsoft per installare quello che voglio dove voglio. Per la precisione ho scoperto il tool msi2xml \/ xml2msi che permette di convertire un file MSI in un file xml e poi fare il processo inverso. come primo esperimento ho modificato ed installato SUS\u2026","rel":"","context":"In &quot;sysadmin&quot;","block_context":{"text":"sysadmin","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/amministrazione-di-sistema\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1547,"url":"https:\/\/www.fullo.net\/blog\/2005\/07\/24\/utenti-di-windows-anonimi\/","url_meta":{"origin":1532,"position":5},"title":"Utenti di Windows anonimi","author":"Francesco Fullone","date":"24\/07\/2005","format":false,"excerpt":"Pi\u00f9 o meno come gli alcolisti anonimi adesso anche gli utenti di windows sapranno dove andare per disintossicarsi. L'unico requisito per iscriversi all'associazione degli utenti di windows anonimi \u00e8 quello di essersi stancati del sistema operativo di Redmond. L'associazione aiuter\u00e0 poi un po' alla volta a disintossicarsi anche da quei\u2026","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1532"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1532\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}