{"id":1616,"date":"2005-08-31T08:35:34","date_gmt":"2005-08-31T06:35:34","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/?p=1616"},"modified":"2005-08-30T17:11:26","modified_gmt":"2005-08-30T15:11:26","slug":"dojo-per-tutti-i-gusti","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/","title":{"rendered":"Dojo per tutti i gusti"},"content":{"rendered":"<p>Rilasciata la nuova <a href=\"http:\/\/dojotoolkit.org\/download\/\">versione di Dojo<\/a>, la 0.1. Di questa versione per venire incontro alle esigenze degli sviluppatori sono state create diverse distribuzioni dedicate a particolari casi. Inoltre insieme a questa release \u00e8 stato aggiornato anche il <a href=\"http:\/\/dojo.jot.com\/WikiHome\">wiki<\/a> con tutta la documentazione ufficiale sul progetto ed alcuni esempi di funzionamento. <\/p>\n<p>[via <a href=\"http:\/\/www.ajaxian.com\/archives\/2005\/08\/dojo_010_has_le.html\">ajaxian blog<\/a>]<\/p>\n<p>ciauz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rilasciata la nuova versione di Dojo, la 0.1. Di questa versione per venire incontro alle esigenze degli sviluppatori sono state create diverse distribuzioni dedicate a particolari casi. Inoltre insieme a questa release \u00e8 stato aggiornato anche il wiki con tutta la documentazione ufficiale sul progetto ed alcuni esempi di funzionamento. [via ajaxian blog] ciauz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14,13],"tags":[2252,539,70],"class_list":["post-1616","post","type-post","status-publish","format-standard","hentry","category-ajax","category-open-source","tag-ajax","tag-dojo","tag-javascript"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dojo per tutti i gusti - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dojo per tutti i gusti - Fullo\" \/>\n<meta property=\"og:description\" content=\"Rilasciata la nuova versione di Dojo, la 0.1. Di questa versione per venire incontro alle esigenze degli sviluppatori sono state create diverse distribuzioni dedicate a particolari casi. Inoltre insieme a questa release \u00e8 stato aggiornato anche il wiki con tutta la documentazione ufficiale sul progetto ed alcuni esempi di funzionamento. [via ajaxian blog] ciauz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2005-08-31T06:35:34+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/08\\\/31\\\/dojo-per-tutti-i-gusti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/08\\\/31\\\/dojo-per-tutti-i-gusti\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"Dojo per tutti i gusti\",\"datePublished\":\"2005-08-31T06:35:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/08\\\/31\\\/dojo-per-tutti-i-gusti\\\/\"},\"wordCount\":57,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"ajax\",\"dojo\",\"javascript\"],\"articleSection\":[\"ajax\",\"open source\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/08\\\/31\\\/dojo-per-tutti-i-gusti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/08\\\/31\\\/dojo-per-tutti-i-gusti\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/08\\\/31\\\/dojo-per-tutti-i-gusti\\\/\",\"name\":\"Dojo per tutti i gusti - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2005-08-31T06:35:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/08\\\/31\\\/dojo-per-tutti-i-gusti\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/08\\\/31\\\/dojo-per-tutti-i-gusti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/08\\\/31\\\/dojo-per-tutti-i-gusti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dojo per tutti i gusti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dojo per tutti i gusti - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/","og_locale":"en_US","og_type":"article","og_title":"Dojo per tutti i gusti - Fullo","og_description":"Rilasciata la nuova versione di Dojo, la 0.1. Di questa versione per venire incontro alle esigenze degli sviluppatori sono state create diverse distribuzioni dedicate a particolari casi. Inoltre insieme a questa release \u00e8 stato aggiornato anche il wiki con tutta la documentazione ufficiale sul progetto ed alcuni esempi di funzionamento. [via ajaxian blog] ciauz","og_url":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/","og_site_name":"Fullo","article_published_time":"2005-08-31T06:35:34+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"Dojo per tutti i gusti","datePublished":"2005-08-31T06:35:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/"},"wordCount":57,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["ajax","dojo","javascript"],"articleSection":["ajax","open source"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/","url":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/","name":"Dojo per tutti i gusti - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2005-08-31T06:35:34+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2005\/08\/31\/dojo-per-tutti-i-gusti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Dojo per tutti i gusti"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-q4","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2558,"url":"https:\/\/www.fullo.net\/blog\/2009\/01\/15\/jquery-13-un-mostro-di-performance\/","url_meta":{"origin":1616,"position":0},"title":"jQuery 1.3, un mostro di performance","author":"Francesco Fullone","date":"15\/01\/2009","format":false,"excerpt":"Ieri \u00e8 stata rilasciata la versione 1.3 di jQuery, a mio parere una delle migliori librerie javascript sul mercato, che vede affiancate alle molte novit\u00e0 un notevolissimo incremento di performance. JQuery 1.3 introduce un nuovo sub-framework per il CSS selector engine, totalmente indipendente dalla libreria e co-sviluppato con gli autori\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"jquery_insertion_benchmark","src":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2009\/01\/jquery_insertion_benchmark-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1824,"url":"https:\/\/www.fullo.net\/blog\/2005\/12\/20\/riassunto-della-settimana\/","url_meta":{"origin":1616,"position":1},"title":"Riassunto della settimana","author":"Francesco Fullone","date":"20\/12\/2005","format":false,"excerpt":"Riassumo qui gli ultimi post fatti su Oss e d\/l, essendo abbastanza impegnato con il trasloco ho dovuto rallentare il ritmo dei post. Li riassumo quindi qui in seguito cercando di raggrupparli nella categorie in cui sarebbero stati inseriti. Open Source rilasciata la versione 2.0 beta 1 di Gaim, supporta\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2328,"url":"https:\/\/www.fullo.net\/blog\/2007\/09\/03\/jquery-114-sempre-meglio\/","url_meta":{"origin":1616,"position":2},"title":"jQuery 1.1.4, sempre meglio!","author":"Francesco Fullone","date":"03\/09\/2007","format":false,"excerpt":"La scorsa settimana \u00e8 stata rilasciata la 4a minor release di jQuery, per la precisione la 1.1.4. A parte i continui miglioramenti di performance ed i bugfix che questa libreria sta continuando ad avere si iniziano ad intravedere le prime modifiche alle API che porteranno all'imminente trunk 1.2. Nello specifico\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1602,"url":"https:\/\/www.fullo.net\/blog\/2005\/08\/21\/ajax-news-2\/","url_meta":{"origin":1616,"position":3},"title":"Ajax news","author":"Francesco Fullone","date":"21\/08\/2005","format":false,"excerpt":"Qualche novit\u00e0 lato ajax: Nuova versione per CPAINT, toolkit indipendente dal linguaggio di backend per implementare soluzioni ajax-enabled. In questa versione il dodice \u00e8 stato praticamente riscritto da capo per migliorarne efficienza e compatibilit\u00e0. Ajax Matters \u00e8 l'ennesimo blog\/portale verticale dedicato interamente ad ajax Script, manuali, tutorial e link su\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1506,"url":"https:\/\/www.fullo.net\/blog\/2005\/07\/07\/ruby-on-rails-013\/","url_meta":{"origin":1616,"position":4},"title":"ruby on rails 0.13","author":"Francesco Fullone","date":"07\/07\/2005","format":false,"excerpt":"E' uscita la nuova versione del framework scritto in ruby che sfrutta in maniera massiva le tecniche ajax. Questa versione di ruby-on-rails a detta degli autori implementa pi\u00f9 di 225 nuove features (molte delle quali derivate dall'utilizzo di script.acul.us) ciuaz","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2226,"url":"https:\/\/www.fullo.net\/blog\/2007\/03\/01\/symfony-10-ed-ajax\/","url_meta":{"origin":1616,"position":5},"title":"Symfony 1.0 ed Ajax","author":"Francesco Fullone","date":"01\/03\/2007","format":false,"excerpt":"E' finalmente stata rilasciata la prima versione stabile di Symfony 1.0. Noto application framework per PHP 5 di cui ho gi\u00e0 discusso pi\u00f9 volte e che ho iniziato ad usare attivamente nell'ultimo mese e mezzo grazie ad un lavoro con Ciccio (mio guru sull'argomento). Tra le magie di questa versione,\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1616"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1616\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}