{"id":1626,"date":"2005-09-04T17:36:48","date_gmt":"2005-09-04T15:36:48","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/?p=1626"},"modified":"2005-09-04T17:49:29","modified_gmt":"2005-09-04T15:49:29","slug":"ajax-rulez-si-ma-con-qualche-dubbio","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/","title":{"rendered":"Ajax rulez? Si, ma con qualche dubbio&#8230;"},"content":{"rendered":"<p>Sto lavorando ad un progetto per un cliente ed ho deciso per alcune form di utilizzare tecniche <a href=\"https:\/\/www.fullo.net\/blog\/search\/ajax\">ajax<\/a>. Per la precisione, visto che la complessit\u00e0 delle funzioni a me necessarie non \u00e8 elevatissima mi sono limitato alla libreria <a href=\"http:\/\/twilightuniverse.com\/2005\/05\/sack-of-ajax\/\">SACK<\/a> per la trasmissione dei dati affiancata da <a href=\"http:\/\/script.aculo.us\/\">Script.aculo.us<\/a> per quel che riguarda le animazioni utili alla visualizzazione degli stessi (faccio un discreto uso\/abuso delle tecniche di <a href=\"https:\/\/www.fullo.net\/blog\/search\/yellow+fading\">yellow fading<\/a>). <\/p>\n<p>Devo dire che ne \u00e8 venuto fuori qualcosa di carino e soprattutto utile per alcuni controlli decisamente noiosi da fare lato server, ricaricare ad esempio una pagina da 100k (immagini incluse) per un username gi\u00e0 esistente mi pare esagerato.<br \/>\n<!--more--><br \/>\nPer andare un po&#8217; pi\u00f9 sullo specifico ho delegato il controllo dei dati immessi in input, la creazione dinamica di form e la visualizzazione di ricerche a <a href=\"https:\/\/www.fullo.net\/blog\/search\/sack\">SACK<\/a>, limitandomi a gestire con php il solo render delle pagine. <\/p>\n<p>E fin qui pare tutto bello, quindi perch\u00e8 i dubbi del titolo? <\/p>\n<p>Perch\u00e8 come avevo espresso tempo fa su qualche ML (non trovo i riferimenti, sorry) <em>dopo un rapido e per niente approfondito test<\/em>, quando ancora ajax era hype e non esisteva <a href=\"http:\/\/blog.joshuaeichorn.com\/ajax-resources\/library\/\">il mare<\/a> di <a href=\"http:\/\/wiki.osafoundation.org\/bin\/view\/Projects\/AjaxLibraries\">librerie<\/a> presenti oggi, questa tecnologia ha un grosso difetto&#8230; dipende interamente dall&#8217;implementazione e dall&#8217;utilizzo di js all&#8217;interno del browser. <strong>E tale implementazione per molti browser datati anche solo 2 anni fa schifo.<\/strong> <\/p>\n<p>Soprassedendo al fatto che metodi come <code>getElementByID<\/code> non funzionino ovunque, ma che comunque il problema sia facilmente aggirabile tramite funzioncine di riconoscimento browser, quello che pi\u00f9 mi infastidisce \u00e8 il supporto fornito <strong>alla funzionalit\u00e0 alla base di ajax<\/strong>, <code><a href=\"http:\/\/www.w3schools.com\/dom\/dom_http.asp\">XMLHttpRequest<\/a><\/code>.<\/p>\n<p>La lista non \u00e8 rassicurante Konqueror &lt; 3.4, Safari &lt; 1.2, Internet Explorer 5.2 (mac) e 5.0.x (winz) ed Opera < 7.6.  non la supportano a pieno o ne hanno un'implementazione buggata.\n\nIl che si traduce in una sola cosa, rifare il lavoro due volte se si vogliono supportare browser un poco vecchi, browser che in Italia <strong>sono utilizzati<\/strong> in moltissime aziende in quanto aggiornare il software non \u00e8 mai una priorit\u00e0. <\/p>\n<p>Ah, gi\u00e0&#8230; <strong>E se js \u00e8 disabilitato?<\/strong> Stesso discorso, tutti i controlli lato client si vanno a far benedire e si torna ai vecchi e sani GET e POST passati direttamente dalla action della form ad una nuova pagina&#8230;<\/p>\n<p>Una possibile soluzione sarebbe quindi quella di creare delle form normali e di appiccicarci dei comportamenti ajax solo se questi sono pienamenti supportati. I quali comportamenti a loro volta  andrebbero a richiamare gli stessi script che invocherebbe la pagina normalmente ma passando 2\/3 parametri in pi\u00f9 per dire che si tratta di richiesta basata su <code>XMLHttpRequest<\/code>. Un discorso per niente banale, e da approfondire accuratamente se non vogliamo fare come 37Signal che per tagliare la testa al toro <a href=\"http:\/\/www.37signals.com\/svn\/archives2\/2005\/03\/driving_the_sta.php\">ha rimosso il supporto a tutti i browser datati da Basecamp<\/a>.<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sto lavorando ad un progetto per un cliente ed ho deciso per alcune form di utilizzare tecniche ajax. Per la precisione, visto che la complessit\u00e0 delle funzioni a me necessarie non \u00e8 elevatissima mi sono limitato alla libreria SACK per la trasmissione dei dati affiancata da Script.aculo.us per quel che riguarda le animazioni utili alla [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14,4,9],"tags":[2252,557,249,558,559,531,560,2244,2248,561,562,415,273],"class_list":["post-1626","post","type-post","status-publish","format-standard","hentry","category-ajax","category-pensieri","category-php","tag-ajax","tag-devel","tag-firefox","tag-ie-5x","tag-javascripts","tag-js","tag-konqueror","tag-pensieri","tag-php","tag-rants","tag-safari","tag-web-20","tag-xmlhttprequest"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ajax rulez? Si, ma con qualche dubbio... - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ajax rulez? Si, ma con qualche dubbio... - Fullo\" \/>\n<meta property=\"og:description\" content=\"Sto lavorando ad un progetto per un cliente ed ho deciso per alcune form di utilizzare tecniche ajax. Per la precisione, visto che la complessit\u00e0 delle funzioni a me necessarie non \u00e8 elevatissima mi sono limitato alla libreria SACK per la trasmissione dei dati affiancata da Script.aculo.us per quel che riguarda le animazioni utili alla [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2005-09-04T15:36:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2005-09-04T15:49:29+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/09\\\/04\\\/ajax-rulez-si-ma-con-qualche-dubbio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/09\\\/04\\\/ajax-rulez-si-ma-con-qualche-dubbio\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"Ajax rulez? Si, ma con qualche dubbio&#8230;\",\"datePublished\":\"2005-09-04T15:36:48+00:00\",\"dateModified\":\"2005-09-04T15:49:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/09\\\/04\\\/ajax-rulez-si-ma-con-qualche-dubbio\\\/\"},\"wordCount\":459,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"ajax\",\"devel\",\"firefox\",\"ie 5.x\",\"javascripts\",\"js\",\"konqueror\",\"pensieri\",\"php\",\"rants\",\"safari\",\"web 2.0\",\"XMLHttpRequest\"],\"articleSection\":[\"ajax\",\"pensieri\",\"php\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/09\\\/04\\\/ajax-rulez-si-ma-con-qualche-dubbio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/09\\\/04\\\/ajax-rulez-si-ma-con-qualche-dubbio\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/09\\\/04\\\/ajax-rulez-si-ma-con-qualche-dubbio\\\/\",\"name\":\"Ajax rulez? Si, ma con qualche dubbio... - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2005-09-04T15:36:48+00:00\",\"dateModified\":\"2005-09-04T15:49:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/09\\\/04\\\/ajax-rulez-si-ma-con-qualche-dubbio\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/09\\\/04\\\/ajax-rulez-si-ma-con-qualche-dubbio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/09\\\/04\\\/ajax-rulez-si-ma-con-qualche-dubbio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ajax rulez? Si, ma con qualche dubbio&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ajax rulez? Si, ma con qualche dubbio... - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/","og_locale":"en_US","og_type":"article","og_title":"Ajax rulez? Si, ma con qualche dubbio... - Fullo","og_description":"Sto lavorando ad un progetto per un cliente ed ho deciso per alcune form di utilizzare tecniche ajax. Per la precisione, visto che la complessit\u00e0 delle funzioni a me necessarie non \u00e8 elevatissima mi sono limitato alla libreria SACK per la trasmissione dei dati affiancata da Script.aculo.us per quel che riguarda le animazioni utili alla [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/","og_site_name":"Fullo","article_published_time":"2005-09-04T15:36:48+00:00","article_modified_time":"2005-09-04T15:49:29+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"Ajax rulez? Si, ma con qualche dubbio&#8230;","datePublished":"2005-09-04T15:36:48+00:00","dateModified":"2005-09-04T15:49:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/"},"wordCount":459,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["ajax","devel","firefox","ie 5.x","javascripts","js","konqueror","pensieri","php","rants","safari","web 2.0","XMLHttpRequest"],"articleSection":["ajax","pensieri","php"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/","url":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/","name":"Ajax rulez? Si, ma con qualche dubbio... - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2005-09-04T15:36:48+00:00","dateModified":"2005-09-04T15:49:29+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2005\/09\/04\/ajax-rulez-si-ma-con-qualche-dubbio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Ajax rulez? Si, ma con qualche dubbio&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-qe","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1671,"url":"https:\/\/www.fullo.net\/blog\/2005\/09\/30\/lavorare-con-javascript\/","url_meta":{"origin":1626,"position":0},"title":"Lavorare con Javascript","author":"Francesco Fullone","date":"30\/09\/2005","format":false,"excerpt":"Visto i miei ultimi lavoretti con javascript ed ajax ho iniziato a cercare un IDE che supportasse la sintassi di questo linguaggio di scripting per il browser. Purtroppo infatti lo Zend Editor, neanche nell'imminente versione 5, supporta la sintassi di js, ed ammetto la mia ignoranza sulla conoscenza dei metodi\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1708,"url":"https:\/\/www.fullo.net\/blog\/2005\/10\/24\/3-anni-di-fulloblog\/","url_meta":{"origin":1626,"position":1},"title":"3 anni di Full(o)bloG","author":"Francesco Fullone","date":"24\/10\/2005","format":false,"excerpt":"Il 19 Ottobre ho festeggiato il terzo anno di Full(o)bloG! Grandi mutamenti sono accorsi in questi anni sia per me che per il blog, lui ha cambiato 3 volte l'hosting, io ho cambiato casa 2 volte e sto per farlo per la terza . Io ho cambiato due lavori, lui\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1874,"url":"https:\/\/www.fullo.net\/blog\/2006\/02\/16\/javascript-ruby-e-php\/","url_meta":{"origin":1626,"position":2},"title":"Javascript, Ruby e PHP","author":"Francesco Fullone","date":"16\/02\/2006","format":false,"excerpt":"Oggi mi sento pigro e quindi pubblico una sfilza di link tecnologici senza commentarli pi\u00f9 di tanto... Mastering Ajax \u00e8 arrivato al terzo appuntamento, il tutorial scritto su IBM DevelopWorks sulle tecniche Ajax sta raggiungendo alcuni spunti interessanti e poco banali e questa volta si parla di header, server requests\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468,"url":"https:\/\/www.fullo.net\/blog\/2005\/06\/18\/ennesima-guida-alluso-di-xmlhttprequest\/","url_meta":{"origin":1626,"position":3},"title":"(ennesima) guida all&#8217;uso di XMLHttpRequest&#8230;","author":"Francesco Fullone","date":"18\/06\/2005","format":false,"excerpt":"su webpasties \u00e8 stata scritta l'ennesima guida all'uso di XMLHttpRequest per creare pagine ajax. La guida \u00e8 moooolto semplice e vuole introdurre gli sviluppatori meno smaliziati all'utilizzo delle tecniche ajax tramite il classico esempio del reperimento dinamico dei CAP\/ZIP Code associati ad una citt\u00e0. ciuaz","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1737,"url":"https:\/\/www.fullo.net\/blog\/2005\/11\/08\/ajax-news-3\/","url_meta":{"origin":1626,"position":4},"title":"Ajax news","author":"Francesco Fullone","date":"08\/11\/2005","format":false,"excerpt":"Da qualche settimana non pubblico nessun link su ajax, ecco qui una lista per risolvere il problema: AFlax \u00e8 uno script js per interfacciarsi direttamente a flash, onestamente non ho ancora studiato come fa ma dai demo sembra interessante.... [via Ajaxian] Napolux mi comunica che ha realizzato un piccolo tutorial,\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2226,"url":"https:\/\/www.fullo.net\/blog\/2007\/03\/01\/symfony-10-ed-ajax\/","url_meta":{"origin":1626,"position":5},"title":"Symfony 1.0 ed Ajax","author":"Francesco Fullone","date":"01\/03\/2007","format":false,"excerpt":"E' finalmente stata rilasciata la prima versione stabile di Symfony 1.0. Noto application framework per PHP 5 di cui ho gi\u00e0 discusso pi\u00f9 volte e che ho iniziato ad usare attivamente nell'ultimo mese e mezzo grazie ad un lavoro con Ciccio (mio guru sull'argomento). Tra le magie di questa versione,\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1626"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1626\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}