{"id":1789,"date":"2005-11-29T12:38:42","date_gmt":"2005-11-29T10:38:42","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/archives\/2005\/11\/29\/wordpress-20-rc1\/"},"modified":"2005-11-29T12:38:42","modified_gmt":"2005-11-29T10:38:42","slug":"wordpress-20-rc1","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/","title":{"rendered":"WordPress 2.0 rc1"},"content":{"rendered":"<p>Lo sviluppo di WordPress 2.0 si fa sempre pi\u00f9 veloce, \u00e8 di poche ore fa la notizia del rilascio della prima release candidate del blog engine scritto in php. E&#8217; possibile scaricare la nuova versione direttamente <a href=\"http:\/\/wordpress.org\/download\/nightly-builds\/\">dal repository ufficiale<\/a> oltre che dal classico subversion.<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo sviluppo di WordPress 2.0 si fa sempre pi\u00f9 veloce, \u00e8 di poche ore fa la notizia del rilascio della prima release candidate del blog engine scritto in php. E&#8217; possibile scaricare la nuova versione direttamente dal repository ufficiale oltre che dal classico subversion. ciuaz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[63,2248,93,854],"class_list":["post-1789","post","type-post","status-publish","format-standard","hentry","category-php","tag-blog","tag-php","tag-wordpress","tag-wordpress-20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wordpress 2.0 rc1 - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wordpress 2.0 rc1 - Fullo\" \/>\n<meta property=\"og:description\" content=\"Lo sviluppo di WordPress 2.0 si fa sempre pi\u00f9 veloce, \u00e8 di poche ore fa la notizia del rilascio della prima release candidate del blog engine scritto in php. E&#8217; possibile scaricare la nuova versione direttamente dal repository ufficiale oltre che dal classico subversion. ciuaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2005-11-29T10:38:42+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/11\\\/29\\\/wordpress-20-rc1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/11\\\/29\\\/wordpress-20-rc1\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"WordPress 2.0 rc1\",\"datePublished\":\"2005-11-29T10:38:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/11\\\/29\\\/wordpress-20-rc1\\\/\"},\"wordCount\":45,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"blog\",\"php\",\"wordpress\",\"wordpress 2.0\"],\"articleSection\":[\"php\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/11\\\/29\\\/wordpress-20-rc1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/11\\\/29\\\/wordpress-20-rc1\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/11\\\/29\\\/wordpress-20-rc1\\\/\",\"name\":\"Wordpress 2.0 rc1 - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2005-11-29T10:38:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/11\\\/29\\\/wordpress-20-rc1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/11\\\/29\\\/wordpress-20-rc1\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2005\\\/11\\\/29\\\/wordpress-20-rc1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordPress 2.0 rc1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wordpress 2.0 rc1 - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/","og_locale":"en_US","og_type":"article","og_title":"Wordpress 2.0 rc1 - Fullo","og_description":"Lo sviluppo di WordPress 2.0 si fa sempre pi\u00f9 veloce, \u00e8 di poche ore fa la notizia del rilascio della prima release candidate del blog engine scritto in php. E&#8217; possibile scaricare la nuova versione direttamente dal repository ufficiale oltre che dal classico subversion. ciuaz","og_url":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/","og_site_name":"Fullo","article_published_time":"2005-11-29T10:38:42+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"WordPress 2.0 rc1","datePublished":"2005-11-29T10:38:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/"},"wordCount":45,"commentCount":2,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["blog","php","wordpress","wordpress 2.0"],"articleSection":["php"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/","url":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/","name":"Wordpress 2.0 rc1 - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2005-11-29T10:38:42+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2005\/11\/29\/wordpress-20-rc1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"WordPress 2.0 rc1"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-sR","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1646,"url":"https:\/\/www.fullo.net\/blog\/2005\/09\/14\/gallery-20\/","url_meta":{"origin":1789,"position":0},"title":"Gallery 2.0","author":"Francesco Fullone","date":"14\/09\/2005","format":false,"excerpt":"Finalmente, dopo quasi due anni di sviluppo, \u00e8 stata rilasciata la versione 2.0 di Gallery, noto script in php per la gestione di gallerie di immagini. Questa versione dell'applicativo, che \u00e8 praticamente una riscrittura da zero del precedente, ha una gestione dei temi e dei template molto potente e basata\u2026","rel":"","context":"In &quot;open source&quot;","block_context":{"text":"open source","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/open-source\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1949,"url":"https:\/\/www.fullo.net\/blog\/2006\/05\/05\/rassegna-di-links-del-venerdi\/","url_meta":{"origin":1789,"position":1},"title":"Rassegna di links del venerd\u00ec","author":"Francesco Fullone","date":"05\/05\/2006","format":false,"excerpt":"Protolize \u00e8 un sito con tutti gli strumenti utili a sviluppare prodotti web 2.0. Su the web 2.0 c'\u00e8 un articolo che mette a confronto i principali framework php del momento. Ennesima web color wheel per l'accostamento di colori acidi (moooolto web 2.0). RTOC \u00e8 una piccola applicazione ajax per\u2026","rel":"","context":"In &quot;ajax&quot;","block_context":{"text":"ajax","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/ajax\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2298,"url":"https:\/\/www.fullo.net\/blog\/2007\/07\/05\/zend-framework-10\/","url_meta":{"origin":1789,"position":2},"title":"Zend Framework 1.0!","author":"Francesco Fullone","date":"05\/07\/2007","format":false,"excerpt":"Lo Zend Framework raggiunge finalmente la stabilit\u00e0 con la versione 1.0. Questo framework per php5 ha di \"comodo\" un buon numero di librerie per accedere a servizi web 2.0 (del.icio.us, flickr, etc) ed una implementazione tutta in php di Lucene. Ma soprattutto, quello che IMHO fa la differenza rispetto ad\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":848,"url":"https:\/\/www.fullo.net\/blog\/2004\/05\/17\/hardened-php\/","url_meta":{"origin":1789,"position":3},"title":"hardened php","author":"Francesco Fullone","date":"17\/05\/2004","format":false,"excerpt":"il progetto hardened php nasce dal desiderio di rendere particolarmente sicura l'implementazione di php su server di alta fascia, il progetto fa s\u00ec che PHP riesca a proteggersi da solo da eventuali script mal realizzati (o realizzati per far eseguire particolari exploit di memoria). Hardened-PHP adds security hardening features to\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2193,"url":"https:\/\/www.fullo.net\/blog\/2007\/01\/15\/wordpress-207\/","url_meta":{"origin":1789,"position":4},"title":"WordPress 2.0.7","author":"Francesco Fullone","date":"15\/01\/2007","format":false,"excerpt":"E' stato rilasciato WordPress 2.0.7, nonostante siano passati pochi giorni dal rilascio della versione 2.0.6 \u00e8 consigliato l'aggiornamento a tutti. Tra l'altro le modifiche da apportare alla propria installazione si contano sulle punta delle dita di un mano... infatti i file incriminati sono solo 6 (ok, due mani...). Ah gi\u00e0,\u2026","rel":"","context":"In &quot;open source&quot;","block_context":{"text":"open source","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/open-source\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1876,"url":"https:\/\/www.fullo.net\/blog\/2006\/02\/16\/php-day-il-call-for-paper-e-aperto\/","url_meta":{"origin":1789,"position":5},"title":"PHP Day il call for paper \u00e8 aperto!","author":"Francesco Fullone","date":"16\/02\/2006","format":false,"excerpt":"Come annunciato qualche giorno fa \u00e8 stato aperto ufficialmente il call for paper del phpDay. Se volete discutere di php davanti ad un centinaio di persone e pensate di avere buone argomentazioni mandateci qualche info. Durante la manifestazione ci saranno 2 differenti percorsi di talk (tenuti parallelamente in due aulee):\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1789"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1789\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}