{"id":1841,"date":"2006-01-12T18:29:59","date_gmt":"2006-01-12T16:29:59","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/archives\/2006\/01\/12\/wordpress-201-in-arrivo\/"},"modified":"2006-01-12T18:29:59","modified_gmt":"2006-01-12T16:29:59","slug":"wordpress-201-in-arrivo","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/","title":{"rendered":"WordPress 2.0.1 in arrivo"},"content":{"rendered":"<p>Come volevasi dimostrare \u00e8 in arrivo la versione 2.0.1 di <a href=\"http:\/\/wordpress.org\">WordPress<\/a> le <a href=\"http:\/\/static.wordpress.org\/builds\/\">nuove nightly builds<\/a> portano infatti la dicitura 2.0.1-a!<\/p>\n<p>Che l&#8217;update del mio blog si avvicini? ;)<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come volevasi dimostrare \u00e8 in arrivo la versione 2.0.1 di WordPress le nuove nightly builds portano infatti la dicitura 2.0.1-a! Che l&#8217;update del mio blog si avvicini? ;) ciuaz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[63,2248,586,93],"class_list":["post-1841","post","type-post","status-publish","format-standard","hentry","category-php","tag-blog","tag-php","tag-update","tag-wordpress"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wordpress 2.0.1 in arrivo - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wordpress 2.0.1 in arrivo - Fullo\" \/>\n<meta property=\"og:description\" content=\"Come volevasi dimostrare \u00e8 in arrivo la versione 2.0.1 di WordPress le nuove nightly builds portano infatti la dicitura 2.0.1-a! Che l&#8217;update del mio blog si avvicini? ;) ciuaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2006-01-12T16:29:59+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/01\\\/12\\\/wordpress-201-in-arrivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/01\\\/12\\\/wordpress-201-in-arrivo\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"WordPress 2.0.1 in arrivo\",\"datePublished\":\"2006-01-12T16:29:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/01\\\/12\\\/wordpress-201-in-arrivo\\\/\"},\"wordCount\":30,\"commentCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"blog\",\"php\",\"update\",\"wordpress\"],\"articleSection\":[\"php\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/01\\\/12\\\/wordpress-201-in-arrivo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/01\\\/12\\\/wordpress-201-in-arrivo\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/01\\\/12\\\/wordpress-201-in-arrivo\\\/\",\"name\":\"Wordpress 2.0.1 in arrivo - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2006-01-12T16:29:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/01\\\/12\\\/wordpress-201-in-arrivo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/01\\\/12\\\/wordpress-201-in-arrivo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/01\\\/12\\\/wordpress-201-in-arrivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordPress 2.0.1 in arrivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wordpress 2.0.1 in arrivo - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/","og_locale":"en_US","og_type":"article","og_title":"Wordpress 2.0.1 in arrivo - Fullo","og_description":"Come volevasi dimostrare \u00e8 in arrivo la versione 2.0.1 di WordPress le nuove nightly builds portano infatti la dicitura 2.0.1-a! Che l&#8217;update del mio blog si avvicini? ;) ciuaz","og_url":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/","og_site_name":"Fullo","article_published_time":"2006-01-12T16:29:59+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"WordPress 2.0.1 in arrivo","datePublished":"2006-01-12T16:29:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/"},"wordCount":30,"commentCount":8,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["blog","php","update","wordpress"],"articleSection":["php"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/","url":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/","name":"Wordpress 2.0.1 in arrivo - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2006-01-12T16:29:59+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2006\/01\/12\/wordpress-201-in-arrivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"WordPress 2.0.1 in arrivo"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-tH","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1899,"url":"https:\/\/www.fullo.net\/blog\/2006\/03\/10\/wordpress-201-security-tips\/","url_meta":{"origin":1841,"position":0},"title":"WordPress 2.0.1 security tips","author":"Francesco Fullone","date":"10\/03\/2006","format":false,"excerpt":"Un piccolo suggerimento di sicurezza se state usando la versione 2.0.1 di Wordpress. DISABILITATE LA REGISTRAZIONE DEGLI UTENTI DIRETTAMENTE DAL BLOG in settimana arriver\u00e0 scaricate la 2.0.2... ciauz","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1856,"url":"https:\/\/www.fullo.net\/blog\/2006\/01\/28\/wordpress-201-rc1\/","url_meta":{"origin":1841,"position":1},"title":"WordPress 2.0.1 RC1","author":"Francesco Fullone","date":"28\/01\/2006","format":false,"excerpt":"E' stata rilasciata la versione ufficiale della prima release candidate di Wordpress 2.0.1. Trovate i file da installare qui, mentre a questo indirizzo il change log. ciuaz","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1829,"url":"https:\/\/www.fullo.net\/blog\/2005\/12\/28\/perche-non-aggiorno-a-wp-20\/","url_meta":{"origin":1841,"position":2},"title":"Perch\u00e8 non aggiorno a Wp 2.0","author":"Francesco Fullone","date":"28\/12\/2005","format":false,"excerpt":"Ecco una piccola lista dei motivi... Ragazzi, come \u00e8 successo per la 1.5 aspettate almeno la 2.0.1 (meglio se 2.0.2)... ciuaz","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1053,"url":"https:\/\/www.fullo.net\/blog\/2004\/10\/12\/fedora-core-3-test-3\/","url_meta":{"origin":1841,"position":3},"title":"Fedora Core 3 Test 3","author":"Francesco Fullone","date":"12\/10\/2004","format":false,"excerpt":"oggi \u00e8 stata rilasciata la test 3 di fedora core 3: * From: Bill Nottingham * To: fedora-announce-list redhat com * Subject: Fedora Core 3 Test 3 available * Date: Mon, 11 Oct 2004 10:25:35 -0400 Fedora Core 3 test 3 is now available. This is the last planned test\u2026","rel":"","context":"In &quot;linux&quot;","block_context":{"text":"linux","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/linux\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2187,"url":"https:\/\/www.fullo.net\/blog\/2007\/01\/11\/in-arrivo-wordpress-207\/","url_meta":{"origin":1841,"position":4},"title":"In arrivo WordPress 2.0.7","author":"Francesco Fullone","date":"11\/01\/2007","format":false,"excerpt":"Se vi state chiedendo perch\u00e8 \u00e8 stata pubblicata oggi l'url della prima seconda release candidate di WordPress 2.0.7, la risposta \u00e8 semplice. E' stato identificato un baco di sicurezza riguardante alcune configurazione (non rare) di virtual hosting. Tra i cambiamenti: worked around a PHP bug for PHP4 < 4.4.3 and\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1435,"url":"https:\/\/www.fullo.net\/blog\/2005\/06\/06\/php-44\/","url_meta":{"origin":1841,"position":5},"title":"php 4.4","author":"Francesco Fullone","date":"06\/06\/2005","format":false,"excerpt":"\u00e8 in arrivo php 4.4, se si da un occhio ai daily snapshot del cvs infatti \u00e8 comparsa la nuova versione di php. Pare che in realt\u00e0 la spiegazione della creazione di un nuovo ramo di sviluppo (4.3.x doveva essere l'ultimo ramo per la versione 4) non derivi dall'aggiunta di\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1841"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1841\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}