{"id":1901,"date":"2006-03-15T15:42:04","date_gmt":"2006-03-15T13:42:04","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/archives\/2006\/03\/15\/impegni-e-ferie\/"},"modified":"2006-03-15T15:42:04","modified_gmt":"2006-03-15T13:42:04","slug":"impegni-e-ferie","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/","title":{"rendered":"Impegni e ferie&#8230;"},"content":{"rendered":"<p>Quest&#8217;ultima settimana ho postato qui molto poco, sono alquanto impegnato con l&#8217;organizzazione di un <a href=\"http:\/\/www.grusp.it\/2006\/03\/13\/online-il-sito-del-phpday-2006\/\">certo evento<\/a> a Bari. Abbiamo finalmente pubblicato il <a href=\"http:\/\/www.phpday.it\/cfp\">call for paper<\/a> (per chi avesse voglia di partecipare come relatore) ed il <a href=\"http:\/\/www.phpday.it\/cfs\">call for sponsors<\/a> ed iniziato ad avere i primi contatti ufficiosi ed ufficiali sui talks. <\/p>\n<p>Pare che, incrociando le dita, in uno di questi verr\u00e0 presentato in anteprima italiana un tutorial sugli <a href=\"https:\/\/www.fullo.net\/blog\/search\/ez+components\">eZ components<\/a> da uno dei suoi stessi sviluppatori. <\/p>\n<p>Sempre a riguardo <a href=\"http:\/\/www.grusp.it\">GrUSP<\/a> abbiamo messo online il nuovo sito e deciso di <a href=\"http:\/\/www.grusp.it\/2006\/03\/14\/comunicazione-ai-soci-2\/\">rinnovare gratuitamente l&#8217;iscrizione<\/a> a tutti i soci per il nuovo anno.<\/p>\n<p>Riprender\u00f2 a scrivere con una certa frequenza probabilmente dalla settimana prossima, a parte qualche post programmato per il weekend, durante il quale sar\u00f2 (a sbronzarmi) a Dublino ospite di <a href=\"http:\/\/www.simonegrassi.net\">Simone<\/a>.<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest&#8217;ultima settimana ho postato qui molto poco, sono alquanto impegnato con l&#8217;organizzazione di un certo evento a Bari. Abbiamo finalmente pubblicato il call for paper (per chi avesse voglia di partecipare come relatore) ed il call for sponsors ed iniziato ad avere i primi contatti ufficiosi ed ufficiali sui talks. Pare che, incrociando le dita, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,9],"tags":[378,2254,493,181,1061,719,2248,1036,75],"class_list":["post-1901","post","type-post","status-publish","format-standard","hentry","category-pensieri","category-php","tag-calendario","tag-eventi","tag-ferie","tag-grusp","tag-impegni","tag-manifestazioni","tag-php","tag-phpday","tag-viaggi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impegni e ferie... - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impegni e ferie... - Fullo\" \/>\n<meta property=\"og:description\" content=\"Quest&#8217;ultima settimana ho postato qui molto poco, sono alquanto impegnato con l&#8217;organizzazione di un certo evento a Bari. Abbiamo finalmente pubblicato il call for paper (per chi avesse voglia di partecipare come relatore) ed il call for sponsors ed iniziato ad avere i primi contatti ufficiosi ed ufficiali sui talks. Pare che, incrociando le dita, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2006-03-15T13:42:04+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/03\\\/15\\\/impegni-e-ferie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/03\\\/15\\\/impegni-e-ferie\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"Impegni e ferie&#8230;\",\"datePublished\":\"2006-03-15T13:42:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/03\\\/15\\\/impegni-e-ferie\\\/\"},\"wordCount\":136,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"calendario\",\"eventi\",\"ferie\",\"grusp\",\"impegni\",\"manifestazioni\",\"php\",\"phpday\",\"viaggi\"],\"articleSection\":[\"pensieri\",\"php\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/03\\\/15\\\/impegni-e-ferie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/03\\\/15\\\/impegni-e-ferie\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/03\\\/15\\\/impegni-e-ferie\\\/\",\"name\":\"Impegni e ferie... - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2006-03-15T13:42:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/03\\\/15\\\/impegni-e-ferie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/03\\\/15\\\/impegni-e-ferie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/03\\\/15\\\/impegni-e-ferie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impegni e ferie&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impegni e ferie... - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/","og_locale":"en_US","og_type":"article","og_title":"Impegni e ferie... - Fullo","og_description":"Quest&#8217;ultima settimana ho postato qui molto poco, sono alquanto impegnato con l&#8217;organizzazione di un certo evento a Bari. Abbiamo finalmente pubblicato il call for paper (per chi avesse voglia di partecipare come relatore) ed il call for sponsors ed iniziato ad avere i primi contatti ufficiosi ed ufficiali sui talks. Pare che, incrociando le dita, [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/","og_site_name":"Fullo","article_published_time":"2006-03-15T13:42:04+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"Impegni e ferie&#8230;","datePublished":"2006-03-15T13:42:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/"},"wordCount":136,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["calendario","eventi","ferie","grusp","impegni","manifestazioni","php","phpday","viaggi"],"articleSection":["pensieri","php"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/","url":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/","name":"Impegni e ferie... - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2006-03-15T13:42:04+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2006\/03\/15\/impegni-e-ferie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Impegni e ferie&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-uF","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2234,"url":"https:\/\/www.fullo.net\/blog\/2007\/03\/19\/concorso-grusp-ed-ossblog\/","url_meta":{"origin":1901,"position":0},"title":"Concorso GrUSP ed OssBlog","author":"Francesco Fullone","date":"19\/03\/2007","format":false,"excerpt":"Il GrUSP, in collaborazione con OSSBlog, ha realizzato un concorso (qui il regolamento) per tutti gli sviluppatori PHP per lanciare il phpDay! Chi realizzer\u00e0 il miglior plugin per uno dei CMS scelti sar\u00e0 premiato con una licenza di Zend Studio Standard e con un anno di tesseramento gratuito al GrUSP.","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"OSSblog+GrUSP = concorso di php","src":"https:\/\/i0.wp.com\/static.blogo.it\/ossblog\/ossblog_grusp_concorso_php.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2159,"url":"https:\/\/www.fullo.net\/blog\/2006\/12\/24\/il-grusp-regala-fonere-e-sconti-su-phparchitect\/","url_meta":{"origin":1901,"position":1},"title":"Il GrUSP regala Fonere e sconti su PHP|Architect!","author":"Francesco Fullone","date":"24\/12\/2006","format":false,"excerpt":"Grazie a Stefano ed a Marco ho attivato per il GrUSP un paio di regalini natalizi. Una Fonera gratuita ed uno sconto casuale tra i 5 ed i 50 dollari sullo shop di php|architect. Il tutto spendibile entro il 31\/12 e per i soli soci dell'associazione. Se quindi non siete\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2430,"url":"https:\/\/www.fullo.net\/blog\/2008\/05\/18\/phpday-alle-porte\/","url_meta":{"origin":1901,"position":2},"title":"phpDay alle porte!","author":"Francesco Fullone","date":"18\/05\/2008","format":false,"excerpt":"Si preannuncia una settimana di inferno, a parte gli impegni lavorativi sempre pi\u00f9 pressanti, tra il 22 ed il 24 Maggio sar\u00f2 infatti in quel di Rimini al phpDay organizzato dal GrUSP di cui sono presidente. Giusto per farvi venire un po' di acquolina vi cito i numeri di quest'anno:\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2016,"url":"https:\/\/www.fullo.net\/blog\/2006\/07\/28\/settembre-e-raduni-di-informatici\/","url_meta":{"origin":1901,"position":3},"title":"Settembre e raduni di informatici","author":"Francesco Fullone","date":"28\/07\/2006","format":false,"excerpt":"Aumenta la lista di raduni di informatici\/fricchettoni\/opensourcisti di settembre. Se fino alla scorsa settimana si parlava solo dell'OpenXP a Cerea (VR) il 30\/9, al quale parteciper\u00f2 con il GrUSP e forse, ancora non ho deciso, come relatore. Adesso sono spuntati anche l'HackIT (finalmente) in quel di Parma il primo weekend\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2271,"url":"https:\/\/www.fullo.net\/blog\/2007\/05\/21\/phpday-2007-qualche-considerazione-sullevento\/","url_meta":{"origin":1901,"position":4},"title":"phpDay 2007, qualche considerazione sull&#8217;evento","author":"Francesco Fullone","date":"21\/05\/2007","format":false,"excerpt":"Ed anche questa \u00e8 finita! Venerd\u00ec scorso si \u00e8 concluso il ciclo lavorativo che mi ha visto (insieme ai ragazzi del GrUSP) perdere il sonno nell'ultimo mese e mezzo. Premetto che quest'anno il phpDay si \u00e8 svolto in maniera \"differente\" rispetto alle scorse edizioni, abbiamo deciso di staccarci dall'ambito universitario\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"P5180095.JPG","src":"https:\/\/i0.wp.com\/farm1.static.flickr.com\/228\/504937952_fa346123e1_m.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3061,"url":"https:\/\/www.fullo.net\/blog\/2013\/04\/01\/due-nuovi-libri-allorizzonte\/","url_meta":{"origin":1901,"position":5},"title":"Due nuovi libri all&#8217;orizzonte","author":"Francesco Fullone","date":"01\/04\/2013","format":false,"excerpt":"Se lo scorso anno, con il GrUSP vi abbiamo deliziato con il nostro primo libro su PHP, quest'anno lo faremo con quello su Javascript. Infatti per FAG Edizioni, insieme ad altri autori, sto scrivendo Javascript Best Practices. Se tutto va bene, ed i ritardatari finiranno per tempo i loro capitoli,\u2026","rel":"","context":"In &quot;altri linguaggi&quot;","block_context":{"text":"altri linguaggi","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/altri-linguaggi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=1901"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/1901\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=1901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=1901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=1901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}