{"id":2033,"date":"2006-08-27T19:46:44","date_gmt":"2006-08-27T17:46:44","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/archives\/2006\/08\/27\/blogdinner-romagna-2\/"},"modified":"2006-09-10T23:23:30","modified_gmt":"2006-09-10T21:23:30","slug":"blogdinner-romagna-2","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/","title":{"rendered":"Blogdinner romagna"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" id=\"image2035\" src=\"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2006\/08\/tortellino.png?w=580\" alt=\"tortellino blog dinner\" align=\"left\" class=\"immagine\" \/> Ok, si \u00e8 tornati dalle ferie e si riparte con l&#8217;organizzazione della cena tra i bloggers romagnoli. <\/p>\n<p><strong>Dove<\/strong><br \/>\nL&#8217;idea \u00e8 di organizzare la cena nella zona tra Faenza e Cesena (passando per Bertinoro). Sicuramente in un agriturismo\/osteria.<\/p>\n<p><strong>Chi<\/strong><br \/>\nPotranno partecipare tutti i possessori di un blog che si registreranno lasciando un commento a questo post. Attualmente si sono registrati: <a href=\"http:\/\/www.disordine.com\/\">Cristian<\/a>, <a href=\"http:\/\/blog.tassoman.com\/\">Tassoman<\/a> e <a href=\"http:\/\/www.dangerous-mind.net\/silvia\">consorte<\/a>, <a href=\"http:\/\/www.cphp.it\">Ciccio<\/a>, <a href=\"http:\/\/www.sardanapalo.net\/wpf\/\">Filo<\/a>, <a href=\"http:\/\/www.lastexxit.com\/\">Dapx<\/a> e <a href=\"http:\/\/daniele.wordpress.com\/\">Daniele<\/a>.<\/p>\n<p>In forse o non confermati: <a href=\"http:\/\/www.lintercapedine.net\/blog\/\">Ardesia<\/a> e <a href=\"http:\/\/www.blublog.it\/\">Luca<\/a>.<\/p>\n<p><strong>Che si mangia<\/strong><br \/>\nIl men\u00f9 sar\u00e0 quello classico da osteria romagnola:<\/p>\n<ul>\n<li>tris di minestre<\/li>\n<li>carnazza<\/li>\n<li>sangiovese<\/li>\n<li>eventuale ciambella con albana per dolce<\/li>\n<\/ul>\n<p><strong>Quando<\/strong><br \/>\nPer comodit\u00e0 di chi lavora un venerd\u00ec, la prima ipotesi \u00e8 venerd\u00ec 22 Settembre. In base ad eventuali votazioni si decider\u00e0 una possibile altra data, anche infrasettimanale.<\/p>\n<p>a seguire qualche faq&#8230;<\/p>\n<p><!--more--><\/p>\n<p><strong>FAQ<\/strong><br \/>\nD: Io non sono romagnolo, posso partecipare?<br \/>\nR: Certo! Neanche io lo sono.. ci abito e basta in Romagna :)<\/p>\n<p>D: Ma si spender\u00e0 molto?<br \/>\nR: Di solito un men\u00f9 del genere oscilla tra i 25-30 euro (mangiando e bevendo bene e molto)<\/p>\n<p>D: Sono vegetariana\/o come faccio?<br \/>\nR: In caso di iscrizione di vegetariani cercheremo di trovare un buon compromesso.<\/p>\n<p>D: Come faccio a venire alla cena? Sono senza macchina!<br \/>\nR: Ci si pu\u00f2 sempre mettere daccordo con blogger che abitano nelle zone limitrofe.<\/p>\n<p>D: Entro quando devo confermare la mia presenza?<br \/>\nR: Entro marted\u00ec 19 Settembre. In quanto bisogner\u00e0 confermare la prenotazione presso l&#8217;agriturismo scelto.<\/p>\n<p>D: ?<br \/>\nR: 42!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ok, si \u00e8 tornati dalle ferie e si riparte con l&#8217;organizzazione della cena tra i bloggers romagnoli. Dove L&#8217;idea \u00e8 di organizzare la cena nella zona tra Faenza e Cesena (passando per Bertinoro). Sicuramente in un agriturismo\/osteria. Chi Potranno partecipare tutti i possessori di un blog che si registreranno lasciando un commento a questo post. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17],"tags":[1401,1416,1417,1418],"class_list":["post-2033","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-blogdinner","tag-blogdinner-romagna","tag-cene","tag-mangiate"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blogdinner romagna - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blogdinner romagna - Fullo\" \/>\n<meta property=\"og:description\" content=\"Ok, si \u00e8 tornati dalle ferie e si riparte con l&#8217;organizzazione della cena tra i bloggers romagnoli. Dove L&#8217;idea \u00e8 di organizzare la cena nella zona tra Faenza e Cesena (passando per Bertinoro). Sicuramente in un agriturismo\/osteria. Chi Potranno partecipare tutti i possessori di un blog che si registreranno lasciando un commento a questo post. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2006-08-27T17:46:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2006-09-10T21:23:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2006\/08\/tortellino.png\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"Blogdinner romagna\",\"datePublished\":\"2006-08-27T17:46:44+00:00\",\"dateModified\":\"2006-09-10T21:23:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/\"},\"wordCount\":241,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2006\\\/08\\\/tortellino.png\",\"keywords\":[\"blogdinner\",\"blogdinner romagna\",\"cene\",\"mangiate\"],\"articleSection\":[\"eventi\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/\",\"name\":\"Blogdinner romagna - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2006\\\/08\\\/tortellino.png\",\"datePublished\":\"2006-08-27T17:46:44+00:00\",\"dateModified\":\"2006-09-10T21:23:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2006\\\/08\\\/tortellino.png\",\"contentUrl\":\"http:\\\/\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2006\\\/08\\\/tortellino.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/08\\\/27\\\/blogdinner-romagna-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogdinner romagna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blogdinner romagna - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/","og_locale":"en_US","og_type":"article","og_title":"Blogdinner romagna - Fullo","og_description":"Ok, si \u00e8 tornati dalle ferie e si riparte con l&#8217;organizzazione della cena tra i bloggers romagnoli. Dove L&#8217;idea \u00e8 di organizzare la cena nella zona tra Faenza e Cesena (passando per Bertinoro). Sicuramente in un agriturismo\/osteria. Chi Potranno partecipare tutti i possessori di un blog che si registreranno lasciando un commento a questo post. [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/","og_site_name":"Fullo","article_published_time":"2006-08-27T17:46:44+00:00","article_modified_time":"2006-09-10T21:23:30+00:00","og_image":[{"url":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2006\/08\/tortellino.png","type":"","width":"","height":""}],"author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"Blogdinner romagna","datePublished":"2006-08-27T17:46:44+00:00","dateModified":"2006-09-10T21:23:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/"},"wordCount":241,"commentCount":12,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"image":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2006\/08\/tortellino.png","keywords":["blogdinner","blogdinner romagna","cene","mangiate"],"articleSection":["eventi"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/","url":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/","name":"Blogdinner romagna - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/#primaryimage"},"image":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2006\/08\/tortellino.png","datePublished":"2006-08-27T17:46:44+00:00","dateModified":"2006-09-10T21:23:30+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/#primaryimage","url":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2006\/08\/tortellino.png","contentUrl":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2006\/08\/tortellino.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/blogdinner-romagna-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Blogdinner romagna"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-wN","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2235,"url":"https:\/\/www.fullo.net\/blog\/2007\/03\/19\/blogdinner-romagna-4\/","url_meta":{"origin":2033,"position":0},"title":"BlogDinner roMagna","author":"Francesco Fullone","date":"19\/03\/2007","format":false,"excerpt":"Si stava pensando (tra me e me) di organizzare la terza blogDinner roMagnola. Come data vista l'attuale assenza di barCamp ed eventi simili ho preso considerato il weekend successivo a pasqua. Chess\u00f2 venerd\u00ec 13 o sabato 14. Il posto potrebbe essere sempre lo stesso, ma si potrebbe anche valutare altro...\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2245,"url":"https:\/\/www.fullo.net\/blog\/2007\/04\/10\/la-blogdinner-romagna-di-fa-il-20-aprile\/","url_meta":{"origin":2033,"position":1},"title":"La BlogDinner roMagna di fa il 20 Aprile!","author":"Francesco Fullone","date":"10\/04\/2007","format":false,"excerpt":"Ultimi giorni per prenotarsi alla blogDinner roMagnola, la data direi che \u00e8 quella del 20 di Aprile (venerd\u00ec), il luogo (vista la mia spiccata passione per gli spostamenti e le novit\u00e0) rimane Faenza. Fatevi vivi, il 18 chiudo le prenotazioni ;) tag della cena: \"blogdinner romagna\" ciuaz","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2442,"url":"https:\/\/www.fullo.net\/blog\/2008\/07\/17\/blogdinner-romagna-summer-season\/","url_meta":{"origin":2033,"position":2},"title":"blogDinner roMagna summer season #2","author":"Francesco Fullone","date":"17\/07\/2008","format":false,"excerpt":"Ecco quindi le ultime informazioni per il blogDinner roMagna: \u201cOstaria del Mare\u201d Via Casette, 5 - Montaletto di Cervia (RA) tel. 0544 965617 - chiuso luned\u00ec Per chi viene da Nord (faenza\/bologna) o da Sud (cattolina\/rimini) il luogo di appuntamento \u00e8 davanti casello di Cesena Sud (mi fanno presente che\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2288,"url":"https:\/\/www.fullo.net\/blog\/2007\/06\/18\/blogdinner-romagna-5\/","url_meta":{"origin":2033,"position":3},"title":"BlogDinner roMagna","author":"Francesco Fullone","date":"18\/06\/2007","format":false,"excerpt":"Me ne aveva riparlato Daniele, poi per\u00f2, come al solito, ce ne siamo dimenticati bellamente ed \u00e8 passato qualche mese... beh.. Siccome a Luglio non si pu\u00f2 non andare a cesenatico a mangiare il pesce (o le alghe se si \u00e8 vegetariani) direi che la prossima blogDinner roMagnola (la quarta\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2036,"url":"https:\/\/www.fullo.net\/blog\/2006\/08\/29\/blogdinner-romagna-3\/","url_meta":{"origin":2033,"position":4},"title":"BlogDinner Romagna","author":"Francesco Fullone","date":"29\/08\/2006","format":false,"excerpt":"Il 22 Settembre 2006 si terr\u00e0, da qualche parte nella zona compresa tra Faenza e Cesena la prima BlogDinner Romagnola. Per iscriversi ed avere maggiori informazioni seguite il link.","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"tortellino blog dinner","src":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2006\/08\/tortellino.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2436,"url":"https:\/\/www.fullo.net\/blog\/2008\/06\/23\/romagna-dinner-strike-again\/","url_meta":{"origin":2033,"position":5},"title":"roMagna blogDinner, strikes again!","author":"Francesco Fullone","date":"23\/06\/2008","format":false,"excerpt":"Ho deciso, \u00e8 tempo di organizzare la prossima roMagna blogDinner. Questa volta si far\u00e0 al mare zona Cesenatico-Rimini (o cmq sulla costa), un gioved\u00ec o venerd\u00ec di fine luglio (direi dopo il 18 per avere tempo di coordinarci). Proposte per luogo e data? Per ora come al solito faccio partire\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=2033"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2033\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=2033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=2033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=2033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}