{"id":2106,"date":"2006-11-01T00:29:18","date_gmt":"2006-10-31T22:29:18","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/archives\/2006\/11\/01\/google-api-per-php-5\/"},"modified":"2006-11-01T00:29:18","modified_gmt":"2006-10-31T22:29:18","slug":"google-api-per-php-5","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/","title":{"rendered":"Google API per PHP 5"},"content":{"rendered":"<p>Google durante l&#8217;ultima <a href=\"http:\/\/zendcon06.kbconferences.com\/\">Zend Conference<\/a> ha reso pubbliche le <a href=\"http:\/\/google-code-updates.blogspot.com\/2006\/10\/google-data-apis-now-with-php.html\">nuove API<\/a> per l&#8217;accesso ai suoi servizi tramite PHP 5. <\/p>\n<p>La cosa interessante \u00e8 che le API in questione saranno incluse nello <a href=\"http:\/\/framework.zend.com\/\">Zend Framework<\/a>, che giusto ieri <a href=\"http:\/\/blog.quantum-star.com\/index.php?\/archives\/241-Zend-Framework-0.20-Preview-Released.html\">ha raggiunto la versione 0.20<\/a> e che al suo interno gi\u00e0 includeva librerie per connettersi a <a href=\"http:\/\/framework.zend.com\/manual\/en\/zend.service.flickr.html\">Flickr<\/a>, <a href=\"http:\/\/framework.zend.com\/manual\/en\/zend.service.amazon.html\">Amazon<\/a> e <a href=\"http:\/\/framework.zend.com\/manual\/en\/zend.service.yahoo.html\">Yahoo<\/a>.<\/p>\n<p>Altro che <a href=\"http:\/\/djangoproject.com\/\">Django<\/a>&#8230; :P<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google durante l&#8217;ultima Zend Conference ha reso pubbliche le nuove API per l&#8217;accesso ai suoi servizi tramite PHP 5. La cosa interessante \u00e8 che le API in questione saranno incluse nello Zend Framework, che giusto ieri ha raggiunto la versione 0.20 e che al suo interno gi\u00e0 includeva librerie per connettersi a Flickr, Amazon e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[225,129,176,2248,1244,126],"class_list":["post-2106","post","type-post","status-publish","format-standard","hentry","category-php","tag-framework","tag-google","tag-opensource","tag-php","tag-service","tag-zend"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Google API per PHP 5 - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google API per PHP 5 - Fullo\" \/>\n<meta property=\"og:description\" content=\"Google durante l&#8217;ultima Zend Conference ha reso pubbliche le nuove API per l&#8217;accesso ai suoi servizi tramite PHP 5. La cosa interessante \u00e8 che le API in questione saranno incluse nello Zend Framework, che giusto ieri ha raggiunto la versione 0.20 e che al suo interno gi\u00e0 includeva librerie per connettersi a Flickr, Amazon e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2006-10-31T22:29:18+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/11\\\/01\\\/google-api-per-php-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/11\\\/01\\\/google-api-per-php-5\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"Google API per PHP 5\",\"datePublished\":\"2006-10-31T22:29:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/11\\\/01\\\/google-api-per-php-5\\\/\"},\"wordCount\":64,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"framework\",\"google\",\"opensource\",\"php\",\"service\",\"zend\"],\"articleSection\":[\"php\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/11\\\/01\\\/google-api-per-php-5\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/11\\\/01\\\/google-api-per-php-5\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/11\\\/01\\\/google-api-per-php-5\\\/\",\"name\":\"Google API per PHP 5 - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2006-10-31T22:29:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/11\\\/01\\\/google-api-per-php-5\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/11\\\/01\\\/google-api-per-php-5\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/11\\\/01\\\/google-api-per-php-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google API per PHP 5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Google API per PHP 5 - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/","og_locale":"en_US","og_type":"article","og_title":"Google API per PHP 5 - Fullo","og_description":"Google durante l&#8217;ultima Zend Conference ha reso pubbliche le nuove API per l&#8217;accesso ai suoi servizi tramite PHP 5. La cosa interessante \u00e8 che le API in questione saranno incluse nello Zend Framework, che giusto ieri ha raggiunto la versione 0.20 e che al suo interno gi\u00e0 includeva librerie per connettersi a Flickr, Amazon e [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/","og_site_name":"Fullo","article_published_time":"2006-10-31T22:29:18+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"Google API per PHP 5","datePublished":"2006-10-31T22:29:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/"},"wordCount":64,"commentCount":2,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["framework","google","opensource","php","service","zend"],"articleSection":["php"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/","url":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/","name":"Google API per PHP 5 - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2006-10-31T22:29:18+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2006\/11\/01\/google-api-per-php-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Google API per PHP 5"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-xY","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2298,"url":"https:\/\/www.fullo.net\/blog\/2007\/07\/05\/zend-framework-10\/","url_meta":{"origin":2106,"position":0},"title":"Zend Framework 1.0!","author":"Francesco Fullone","date":"05\/07\/2007","format":false,"excerpt":"Lo Zend Framework raggiunge finalmente la stabilit\u00e0 con la versione 1.0. Questo framework per php5 ha di \"comodo\" un buon numero di librerie per accedere a servizi web 2.0 (del.icio.us, flickr, etc) ed una implementazione tutta in php di Lucene. Ma soprattutto, quello che IMHO fa la differenza rispetto ad\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1700,"url":"https:\/\/www.fullo.net\/blog\/2005\/10\/19\/php-collaboration-project\/","url_meta":{"origin":2106,"position":1},"title":"PHP Collaboration Project","author":"Francesco Fullone","date":"19\/10\/2005","format":false,"excerpt":"Visto il putiferio fatto dall'annuncio di ieri, la Zend ci ha riflettuto un attimo e ha creato un'apposita area sul suo sito dove si cerca di spiegare punto per punto cosa saranno e come verranno gestiti sia il framework che il nuovo IDE. Onestamente non mi sembra che spieghi molto...\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1940,"url":"https:\/\/www.fullo.net\/blog\/2006\/04\/24\/zend-framework-013-e-nuovo-sito\/","url_meta":{"origin":2106,"position":2},"title":"Zend Framework 0.13 e nuovo sito","author":"Francesco Fullone","date":"24\/04\/2006","format":false,"excerpt":"Lo Zend Framework, che arriva alla release 0.13, ha finalmente un logo ed un nuovo sito (sempre pi\u00f9 ricco di contenuti). In questa nuova release il modulo che sfrutta Lucene come search engine \u00e8 entrato a far parte del tree ufficiale ed inoltre i moduli relativi alla gestione delle email\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2120,"url":"https:\/\/www.fullo.net\/blog\/2006\/11\/15\/zend-studio-55-beta\/","url_meta":{"origin":2106,"position":3},"title":"Zend Studio 5.5 beta","author":"Francesco Fullone","date":"15\/11\/2006","format":false,"excerpt":"E' stata rilasciata la nuova beta di Zend Studio 5.5, beta che come al solito prover\u00f2 immediatamente sto gi\u00e0 provando... ;). Tra le cose interessanti una migliore gestione di CVS\/SVN, l'inclusione dello Zend Framework e dello Zend Platform di cui ora compaiono i men\u00f9 nell'interfaccia inoltre \u00e8 stato inserito supporto\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1944,"url":"https:\/\/www.fullo.net\/blog\/2006\/05\/02\/php-news-4\/","url_meta":{"origin":2106,"position":4},"title":"PHP news","author":"Francesco Fullone","date":"02\/05\/2006","format":false,"excerpt":"Ultimamente ho scritto poco... un poco a causa dei sempre maggiori impegni lavorativi un poco perch\u00e8 nel tempo libero (visto che non piove) cerco di uscire a prendere aria fresca.. ecco comunque una serie di informazioni sul mondo del PHP che avevo dimenticato di citare... E' uscito PHP 5.1.3, una\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1799,"url":"https:\/\/www.fullo.net\/blog\/2005\/12\/05\/zend-framework-review\/","url_meta":{"origin":2106,"position":5},"title":"Zend Framework review","author":"Francesco Fullone","date":"05\/12\/2005","format":false,"excerpt":"Su phpDeveloper c'\u00e8 una recensione abbastanza accurata sullo Zend Framework. Sembra che ci siano alcuni aspetti molto interessanti nel framework come un motore di ricerca interno simile a lucene del progetto Apache, la non necessit\u00e0 di doversi appoggiare a mod_rewrite ed un dataobject layer per accedere ai dbms. [update] ne\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=2106"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2106\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=2106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=2106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=2106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}