{"id":2160,"date":"2006-12-27T17:59:27","date_gmt":"2006-12-27T15:59:27","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/archives\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/"},"modified":"2006-12-27T18:05:40","modified_gmt":"2006-12-27T16:05:40","slug":"remail-il-mio-client-mail-ideale","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/","title":{"rendered":"ReMail, il mio client mail ideale"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.research.ibm.com\/remail\/images\/introduction.jpg?w=580\" alt=\"reMail\" align=\"left\" class=\"immagine\" \/> Da quello che posso vedere negli <a href=\"http:\/\/domino.research.ibm.com\/cambridge\/research.nsf\/99751d8eb5a20c1f852568db004efc90\/801202452f8bc73b8525698a0066cba4?OpenDocument\">IBM Research Lab<\/a> hanno progettato il mio client di posta ideale. <\/p>\n<p>Compatibile con qualsiasi tipo di server, che riesce a gestire grossi quantitativi di email e di organizzarla al meglio. Ricco di strumenti per gestire il proprio lavoro (note sulle email, calendario, etc). E con una spiccata propensione alla gestione dei thread (stupenda l&#8217;idea dei <a href=\"http:\/\/www.research.ibm.com\/remail\/threadarcs.html\">thread arcs<\/a>). <\/p>\n<p>L&#8217;unico difetto \u00e8 che ad oggi <strong><a href=\"http:\/\/www.research.ibm.com\/remail\/index.html\">ReMail<\/a> non esiste<\/strong>&#8230; sigh&#8230;<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da quello che posso vedere negli IBM Research Lab hanno progettato il mio client di posta ideale. Compatibile con qualsiasi tipo di server, che riesce a gestire grossi quantitativi di email e di organizzarla al meglio. Ricco di strumenti per gestire il proprio lavoro (note sulle email, calendario, etc). E con una spiccata propensione alla [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[1616,132,729],"class_list":["post-2160","post","type-post","status-publish","format-standard","hentry","category-tecnologia","tag-domino","tag-email","tag-ibm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ReMail, il mio client mail ideale - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ReMail, il mio client mail ideale - Fullo\" \/>\n<meta property=\"og:description\" content=\"Da quello che posso vedere negli IBM Research Lab hanno progettato il mio client di posta ideale. Compatibile con qualsiasi tipo di server, che riesce a gestire grossi quantitativi di email e di organizzarla al meglio. Ricco di strumenti per gestire il proprio lavoro (note sulle email, calendario, etc). E con una spiccata propensione alla [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2006-12-27T15:59:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2006-12-27T16:05:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.research.ibm.com\/remail\/images\/introduction.jpg\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"ReMail, il mio client mail ideale\",\"datePublished\":\"2006-12-27T15:59:27+00:00\",\"dateModified\":\"2006-12-27T16:05:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/\"},\"wordCount\":81,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.research.ibm.com\\\/remail\\\/images\\\/introduction.jpg\",\"keywords\":[\"domino\",\"email\",\"ibm\"],\"articleSection\":[\"tecnologia\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/\",\"name\":\"ReMail, il mio client mail ideale - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.research.ibm.com\\\/remail\\\/images\\\/introduction.jpg\",\"datePublished\":\"2006-12-27T15:59:27+00:00\",\"dateModified\":\"2006-12-27T16:05:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.research.ibm.com\\\/remail\\\/images\\\/introduction.jpg\",\"contentUrl\":\"http:\\\/\\\/www.research.ibm.com\\\/remail\\\/images\\\/introduction.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/27\\\/remail-il-mio-client-mail-ideale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ReMail, il mio client mail ideale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ReMail, il mio client mail ideale - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/","og_locale":"en_US","og_type":"article","og_title":"ReMail, il mio client mail ideale - Fullo","og_description":"Da quello che posso vedere negli IBM Research Lab hanno progettato il mio client di posta ideale. Compatibile con qualsiasi tipo di server, che riesce a gestire grossi quantitativi di email e di organizzarla al meglio. Ricco di strumenti per gestire il proprio lavoro (note sulle email, calendario, etc). E con una spiccata propensione alla [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/","og_site_name":"Fullo","article_published_time":"2006-12-27T15:59:27+00:00","article_modified_time":"2006-12-27T16:05:40+00:00","og_image":[{"url":"http:\/\/www.research.ibm.com\/remail\/images\/introduction.jpg","type":"","width":"","height":""}],"author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"ReMail, il mio client mail ideale","datePublished":"2006-12-27T15:59:27+00:00","dateModified":"2006-12-27T16:05:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/"},"wordCount":81,"commentCount":7,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"image":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/#primaryimage"},"thumbnailUrl":"http:\/\/www.research.ibm.com\/remail\/images\/introduction.jpg","keywords":["domino","email","ibm"],"articleSection":["tecnologia"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/","url":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/","name":"ReMail, il mio client mail ideale - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/#primaryimage"},"image":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/#primaryimage"},"thumbnailUrl":"http:\/\/www.research.ibm.com\/remail\/images\/introduction.jpg","datePublished":"2006-12-27T15:59:27+00:00","dateModified":"2006-12-27T16:05:40+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/#primaryimage","url":"http:\/\/www.research.ibm.com\/remail\/images\/introduction.jpg","contentUrl":"http:\/\/www.research.ibm.com\/remail\/images\/introduction.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/27\/remail-il-mio-client-mail-ideale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"ReMail, il mio client mail ideale"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-yQ","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1905,"url":"https:\/\/www.fullo.net\/blog\/2006\/03\/16\/pim-gestire-le-fatture-con-symfony\/","url_meta":{"origin":2160,"position":0},"title":"P.I.M. gestire le fatture con symfony","author":"Francesco Fullone","date":"16\/03\/2006","format":false,"excerpt":"Ciccio ha finalmente rilasciato la prima versione di P.I.M. un softwarillo scritto in php usando il framework Symfony (di cui ho gi\u00e0 parlato in diverse occasioni) per la gestione delle fatture. Il progetto \u00e8 nato perch\u00e8 il soggetto in questione (diventato da poco libero professionista e mio esperto eZ publish\u2026","rel":"","context":"In &quot;open source&quot;","block_context":{"text":"open source","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/open-source\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2115,"url":"https:\/\/www.fullo.net\/blog\/2006\/11\/13\/come-gestire-la-rivalsa-previdenziale\/","url_meta":{"origin":2160,"position":1},"title":"Come gestire la rivalsa previdenziale?","author":"Francesco Fullone","date":"13\/11\/2006","format":false,"excerpt":"Premetto che questo post \u00e8 indirizzato soprattutto ai liberi professionisti che leggono il mio blog. Oggi parlando con un mio collega \u00e8 uscito fuori il discorso rivalsa previdenziale del 4% e di come sia gestita diversamente dai professionisti italiani. Il mio punto di vista (indotto dopo luuuunghe discussioni con i\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2805,"url":"https:\/\/www.fullo.net\/blog\/2011\/08\/17\/la-sottile-arte-della-contrattazione-con-asce-bipenne-ai-tempi-del-web-2-0\/","url_meta":{"origin":2160,"position":2},"title":"La sottile arte della contrattazione ai tempi del web 2.0","author":"Francesco Fullone","date":"17\/08\/2011","format":false,"excerpt":"Con la mia azienda le cose vanno abbastanza bene e per questo motivo, mio malgrado, ho dovuto ridurre drasticamente le mie ore da sviluppatore per dedicarmi ad attivit\u00e0 un tempo da me considerate marginali (alla produzione di buon codice) ma ora indispensabili al fine favorire ed aiutare una sana crescita\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2499,"url":"https:\/\/www.fullo.net\/blog\/2008\/11\/07\/geekness-varia-ed-avariata\/","url_meta":{"origin":2160,"position":3},"title":"Geekness varia (ed avariata)","author":"Francesco Fullone","date":"07\/11\/2008","format":false,"excerpt":"Molti penseranno che l'autore di questo blog, l'esimio sottoscritto, non abbia pi\u00f9 voglia di scrivere nulla. La realt\u00e0 \u00e8 ben diversa. Sto scrivendo tantissimo, peccato che finisca tutto in draft e li rimanga per mesi. Siccome mi sono stancato di vedere tutti i post a met\u00e0, qui di seguito troverete\u2026","rel":"","context":"In &quot;lifehack&quot;","block_context":{"text":"lifehack","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/lifehack\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3482,"url":"https:\/\/www.fullo.net\/blog\/2020\/05\/17\/eventbrite-il-prossimo-blockbuster\/","url_meta":{"origin":2160,"position":4},"title":"Eventbrite, il prossimo Blockbuster?","author":"Francesco Fullone","date":"17\/05\/2020","format":false,"excerpt":"Che la pandemia abbia portato un deciso scossone al mondo degli eventi \u00e8 ormai evidente a tutti, se alcune aziende, quelle pi\u00f9 piccole, hanno chiuso i battenti altre stanno convertendo, quando possibile, i propri eventi di punta in digitale o li stanno posponendo a fine anno affiancando e spingendo, nel\u2026","rel":"","context":"In &quot;business design&quot;","block_context":{"text":"business design","link":"https:\/\/www.fullo.net\/blog\/category\/entrepreneurship\/business-design\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2020\/05\/eventbrite-vs-blockbuster-1.jpg?fit=941%2C528&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2020\/05\/eventbrite-vs-blockbuster-1.jpg?fit=941%2C528&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2020\/05\/eventbrite-vs-blockbuster-1.jpg?fit=941%2C528&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2020\/05\/eventbrite-vs-blockbuster-1.jpg?fit=941%2C528&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4206,"url":"https:\/\/www.fullo.net\/blog\/2024\/04\/12\/futures-cone-e-okr-come-prevedere-e-gestire-il-futuro\/","url_meta":{"origin":2160,"position":5},"title":"Futures Cone e OKR, come prevedere e gestire il futuro","author":"Francesco Fullone","date":"12\/04\/2024","format":false,"excerpt":"Come possiamo utilizzare i Coni dei Futuri per rappresentare Obiettivi, Risultati Chiave e Iniziative della nostra azienda? Cercher\u00f2 di spiegarlo in questo post, forse pi\u00f9 a me che a voi, al fine di trovare una rappresentazione visuale che ci aiuti a capire meglio cosa sono le iniziative degli OKR.","rel":"","context":"In &quot;business design&quot;","block_context":{"text":"business design","link":"https:\/\/www.fullo.net\/blog\/category\/entrepreneurship\/business-design\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/04\/Visual-representation-of-Futures-Cone-concept-with-objectives-key-results-and-initiatives-i.png?fit=1024%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/04\/Visual-representation-of-Futures-Cone-concept-with-objectives-key-results-and-initiatives-i.png?fit=1024%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/04\/Visual-representation-of-Futures-Cone-concept-with-objectives-key-results-and-initiatives-i.png?fit=1024%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/04\/Visual-representation-of-Futures-Cone-concept-with-objectives-key-results-and-initiatives-i.png?fit=1024%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=2160"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2160\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=2160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=2160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=2160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}