{"id":2165,"date":"2006-12-31T17:48:16","date_gmt":"2006-12-31T15:48:16","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/archives\/2006\/12\/31\/php-e-sicurezza\/"},"modified":"2006-12-31T17:48:16","modified_gmt":"2006-12-31T15:48:16","slug":"php-e-sicurezza","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/","title":{"rendered":"PHP e sicurezza"},"content":{"rendered":"<p>Ultimamente vuoi per viaggi e vuoi per lavoro ho tralasciato uno degli argomenti principali del mio blog il <a href=\"https:\/\/www.fullo.net\/blog\/archives\/category\/tecnologia\/php\/\">PHP<\/a>. Me ne scuso con i miei lettori facendo un piccolo resoconto su quello che \u00e8 successo negli ultimi mesi in ambito sicurezza.<\/p>\n<p><!--more--><\/p>\n<p>Innanzitutto <a href=\"http:\/\/blog.php-security.org\/archives\/61-Retired-from-securityphp.net.html\">Stefen Esser<\/a> ha lasciato il gruppo relativo alla sicurezza del progetto PHP, questo perch\u00e8 non abbastanza rapido a risolvere problemi e con la tendenza a fare full disclosure  su alcune falle dell&#8217;interprete. La cosa mi ha lasciato con un po&#8217; di amaro in bocca, penso che Stefen sia uno dei pi\u00f9 attivi nel settore security e vederlo uscire dal gotha degli sviluppatori non \u00e8 molto facile da accettare. <\/p>\n<p>Fortunatamente lo sviluppo di <a href=\"http:\/\/www.suhosin.org\/\">Suhosin<\/a> ha visto un discreto incremento di velocit\u00e0 tanto che negli ultimi giorni sono state rilasciate versioni di questo modulo che permettono <a href=\"http:\/\/blog.php-security.org\/archives\/67-Heuristic-SQL-Injection-Detection-for-Suhosin.html\">rudimentali procedure euristiche<\/a> per identificare SQL Injection. Purtroppo nessun hosting provider attualmente include\/abilita Suhosin&#8230;<\/p>\n<p>Per prevenire un grosso baco presente in molte versioni di PHP <a href=\"https:\/\/www.fullo.net\/blog\/archives\/2006\/11\/04\/aggiornate-php-e-fatelo-in-fretta\/\">\u00e8 stata rilasciata la versione 5.2<\/a> quest&#8217;ultima ha introdotto tra l&#8217;altro l&#8217;<a href=\"http:\/\/it2.php.net\/filter\">estensione Filter<\/a>. Questa estensione permette di analizzare l&#8217;input e di ripulirlo per eventuali riutilizzi. Purtroppo \u00e8 un&#8217;estensione del linguaggio e quindi comporta (come al solito) che i vari hosting provider la utilizzino all&#8217;interno dei loro pacchetti e che ne ricompilino il modulo ad ogni aggiornamento. Inoltre alcune politiche di utilizzo della stessa mi rimangono oscure e poco user friendly, senza contare che abilitare di default un <a href=\"http:\/\/www.christopher-kunz.de\/serendipity\/archives\/116-Thoughts-on-extfilter-et-al..html\">modulo immaturo<\/a> mi pare controproducente all&#8217;immagine dello stesso. Anche in questo caso rimango abbastanza daccordo con <a href=\"http:\/\/blog.php-security.org\/archives\/64-Why-extfilter.html\">Stefan<\/a> e suggerirei di utilizzare una libreria in user space per fare l&#8217;analisi e la validazione dell&#8217;input che rimanga trasparente all&#8217;applicazione e che non ne complichi ulteriormente il codice.<\/p>\n<p>Tra l&#8217;altro una libreria del genere, completamente separata da tutti gli attuali framework in circolazione e quindi utilizzabile senza dipendenze particolari, far\u00e0 parte del progetto <a href=\"http:\/\/www.hardened-php.net\/library\/index.html\">Hardened-PHP<\/a> e sar\u00e0 rilasciata durante il 2007.<\/p>\n<p>Per finire il <a href=\"http:\/\/phpsec.org\/\">PHP Security Consortium<\/a> ha continuato la sua opera di evangelizzazione aggiornando abbastanza frequentemente il suo <a href=\"http:\/\/phpsec.org\/projects\/vulnerabilities\/securityfocus.html\">SecurityFocus<\/a> e rilasciando una piccola applicazione chiamata <a href=\"http:\/\/phpsec.org\/projects\/phpsecinfo\/index.html\"><code>phpsecinfo()<\/code><\/a>, che pi\u00f9 o meno come fa la funzione <code>phpinfo()<\/code>, restituisce una lista di informazioni sulla propria installazione di PHP aggiungendo inoltre qualche tips all&#8217;hardening della stessa.<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ultimamente vuoi per viaggi e vuoi per lavoro ho tralasciato uno degli argomenti principali del mio blog il PHP. Me ne scuso con i miei lettori facendo un piccolo resoconto su quello che \u00e8 successo negli ultimi mesi in ambito sicurezza.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[2248,307,2250],"class_list":["post-2165","post","type-post","status-publish","format-standard","hentry","category-php","tag-php","tag-sicurezza","tag-webdev"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PHP e sicurezza - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PHP e sicurezza - Fullo\" \/>\n<meta property=\"og:description\" content=\"Ultimamente vuoi per viaggi e vuoi per lavoro ho tralasciato uno degli argomenti principali del mio blog il PHP. Me ne scuso con i miei lettori facendo un piccolo resoconto su quello che \u00e8 successo negli ultimi mesi in ambito sicurezza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2006-12-31T15:48:16+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/31\\\/php-e-sicurezza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/31\\\/php-e-sicurezza\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"PHP e sicurezza\",\"datePublished\":\"2006-12-31T15:48:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/31\\\/php-e-sicurezza\\\/\"},\"wordCount\":377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"php\",\"sicurezza\",\"webdev\"],\"articleSection\":[\"php\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/31\\\/php-e-sicurezza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/31\\\/php-e-sicurezza\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/31\\\/php-e-sicurezza\\\/\",\"name\":\"PHP e sicurezza - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2006-12-31T15:48:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/31\\\/php-e-sicurezza\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/31\\\/php-e-sicurezza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2006\\\/12\\\/31\\\/php-e-sicurezza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PHP e sicurezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PHP e sicurezza - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/","og_locale":"en_US","og_type":"article","og_title":"PHP e sicurezza - Fullo","og_description":"Ultimamente vuoi per viaggi e vuoi per lavoro ho tralasciato uno degli argomenti principali del mio blog il PHP. Me ne scuso con i miei lettori facendo un piccolo resoconto su quello che \u00e8 successo negli ultimi mesi in ambito sicurezza.","og_url":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/","og_site_name":"Fullo","article_published_time":"2006-12-31T15:48:16+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"PHP e sicurezza","datePublished":"2006-12-31T15:48:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["php","sicurezza","webdev"],"articleSection":["php"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/","url":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/","name":"PHP e sicurezza - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2006-12-31T15:48:16+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2006\/12\/31\/php-e-sicurezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"PHP e sicurezza"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-yV","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":328,"url":"https:\/\/www.fullo.net\/blog\/2003\/07\/01\/phplinksphp-day\/","url_meta":{"origin":2165,"position":0},"title":"php::Links(&#8216;php Day&#8217;)","author":"Francesco Fullone","date":"01\/07\/2003","format":false,"excerpt":"I ragazzi della PHP-ML stanno cercando di realizzare il primo PHP-Day italiano! :D ecci una bozza di quello che sar\u00e0 il programma: PHP Day 2003. 24 Ottobre 2003 Il PhpDay si propone di dare visibilit\u00e0 al linguaggio di programmazione dedicato al web che negli ultimi mesi sta conoscendo il suo\u2026","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2116,"url":"https:\/\/www.fullo.net\/blog\/2006\/11\/14\/e-piu-forte-di-me\/","url_meta":{"origin":2165,"position":1},"title":"\u00c9 pi\u00f9 forte di me&#8230;","author":"Francesco Fullone","date":"14\/11\/2006","format":false,"excerpt":"Ma quando qualcuno mi dice: Php \u00e8 un linguaggio \"giocattolo\", va bene per delle cose rapide, ma quando bisogna fare delle cose ad un certo livello \u00e8 pi\u00f9 saggio utilizzare Java. Questo perch\u00e9 Php non \u00e8 un linguaggio completo, ad esempio il supporto per la programmazione ad oggetti \u00e8 ridicolo...\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2100,"url":"https:\/\/www.fullo.net\/blog\/2006\/10\/28\/securityday-e-linuxday-missione-compiuta\/","url_meta":{"origin":2165,"position":2},"title":"SecurityDay e LinuxDay, missione compiuta.","author":"Francesco Fullone","date":"28\/10\/2006","format":false,"excerpt":"Finalmente sono finite le due giornate dedicate ai talk sulla sicurezza e l'opensource tenutesi a Cesena. Come ogni hanno l'affluenza dall'esterno \u00e8 stata positiva, meno positiva quella degli studenti di scienze dell'informazione che, a parte rare eccezioni, hanno preferito continuare a giocare al biliardo di yahoo! in laboratorio. Le considerazioni\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"Security day a cesena","src":"https:\/\/i0.wp.com\/static.flickr.com\/88\/280422656_c38e38a221_t.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1712,"url":"https:\/\/www.fullo.net\/blog\/2005\/10\/26\/php-sicurezza-e-quantaltro\/","url_meta":{"origin":2165,"position":3},"title":"php, sicurezza e quantaltro&#8230;","author":"Francesco Fullone","date":"26\/10\/2005","format":false,"excerpt":"Continuano gli sproloqui e le wishlist sul futuro framework di Zend, per ora ne parlano: Wez Furlong (il quale per\u00f2 da anche le prime spiegazioni di come sar\u00e0 veramente) John Lim Chris Shifflet con una whishlist sulla sicurezza Ancora qualche links (forse qualcuno vecchio) sulla sicurezza delle applicazioni web: su\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3083,"url":"https:\/\/www.fullo.net\/blog\/2013\/05\/27\/creare-un-ecosistema-sano-e-possibile\/","url_meta":{"origin":2165,"position":4},"title":"Creare un ecosistema sano, \u00e8 possibile.","author":"Francesco Fullone","date":"27\/05\/2013","format":false,"excerpt":"Qualche tempo fa, durante una riunione dell'xpug romagnolo (che ora ha anche una pagina su G+), emerse il discorso sul rimanere a combattere piuttosto che emigrare. La serata, piuttosto che vergere sul classico auto compatimento \u00e8 stata interessante ed ha portato a diversi punti chiave su cui lavorare. Il pi\u00f9\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":211,"url":"https:\/\/www.fullo.net\/blog\/2003\/04\/26\/phplinksphp-nuke\/","url_meta":{"origin":2165,"position":5},"title":"php::Links(&#8216;php-nuke&#8217;)","author":"Francesco Fullone","date":"26\/04\/2003","format":false,"excerpt":"Fernando Burzi, autore dell'amato\/odiato PHP-Nuke, ha scritto in questo articolo che la prossima versione del suo CMS sar\u00e0 in closed source! Burzi \u00e8 infatti intenzionato ad offuscare il codice usando un encoder come quello della Zend, tra le motivazioni spiccano la necessit\u00e0 di aumentare la sicurezza di Nuke (non sai\u2026","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=2165"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2165\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=2165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=2165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=2165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}