{"id":2264,"date":"2007-05-13T01:01:55","date_gmt":"2007-05-13T00:01:55","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/archives\/2007\/05\/13\/twitter-fullonet-e-la-7\/"},"modified":"2007-05-13T01:01:55","modified_gmt":"2007-05-13T00:01:55","slug":"twitter-fullonet-e-la-7","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/","title":{"rendered":"Twitter, Fullo.net e La 7"},"content":{"rendered":"<p>Oggi al telegiornale di <a href=\"http:\/\/www.la7.it\">La7<\/a> delle 13.00 si \u00e8 parlato di Twitter, e per descriverne il funzionamento hanno citato il presente blog e le <a href=\"https:\/\/www.fullo.net\/blog\/search\/twitter+rules\">regole<\/a> che pubblicai tempo addietro e che ultimamente <a href=\"http:\/\/www.levysoft.it\/archivio\/2007\/05\/11\/usi-e-costumi-di-twitter-ecco-perche-non-dovrebbe-valere-la-regola-della-terza-persona\/\">LevySoft<\/a> ha ridiscusso.<\/p>\n<p>Nel proseguimento del post \u00e8 presente la parte del filmato tratta dal TG.<\/p>\n<p><!--more--><\/p>\n<p>Per quanto riguarda il discorso introdotto da Antonio direi che il <a href=\"https:\/\/www.fullo.net\/blog\/archives\/2007\/01\/05\/il-perche-delle-sette-regole-doro-di-twitter\/\">vecchio post a riguardo<\/a> spiega tutto, per la terza persona considero come fonte ufficiale il web di twitter. I programmi di terze parti o i feed dovrebbero adattarsi a quello ;)<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi al telegiornale di La7 delle 13.00 si \u00e8 parlato di Twitter, e per descriverne il funzionamento hanno citato il presente blog e le regole che pubblicai tempo addietro e che ultimamente LevySoft ha ridiscusso. Nel proseguimento del post \u00e8 presente la parte del filmato tratta dal TG.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[16,5],"tags":[1757,1758,1759,1760,1761,1624],"class_list":["post-2264","post","type-post","status-publish","format-standard","hentry","category-lifehack","category-tecnologia","tag-citazioni","tag-discussioni","tag-la7","tag-telegiornale","tag-tg7","tag-twitter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Twitter, Fullo.net e La 7 - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Twitter, Fullo.net e La 7 - Fullo\" \/>\n<meta property=\"og:description\" content=\"Oggi al telegiornale di La7 delle 13.00 si \u00e8 parlato di Twitter, e per descriverne il funzionamento hanno citato il presente blog e le regole che pubblicai tempo addietro e che ultimamente LevySoft ha ridiscusso. Nel proseguimento del post \u00e8 presente la parte del filmato tratta dal TG.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2007-05-13T00:01:55+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2007\\\/05\\\/13\\\/twitter-fullonet-e-la-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2007\\\/05\\\/13\\\/twitter-fullonet-e-la-7\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"Twitter, Fullo.net e La 7\",\"datePublished\":\"2007-05-13T00:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2007\\\/05\\\/13\\\/twitter-fullonet-e-la-7\\\/\"},\"wordCount\":92,\"commentCount\":11,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"keywords\":[\"citazioni\",\"discussioni\",\"la7\",\"telegiornale\",\"tg7\",\"twitter\"],\"articleSection\":[\"lifehack\",\"tecnologia\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2007\\\/05\\\/13\\\/twitter-fullonet-e-la-7\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2007\\\/05\\\/13\\\/twitter-fullonet-e-la-7\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2007\\\/05\\\/13\\\/twitter-fullonet-e-la-7\\\/\",\"name\":\"Twitter, Fullo.net e La 7 - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2007-05-13T00:01:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2007\\\/05\\\/13\\\/twitter-fullonet-e-la-7\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2007\\\/05\\\/13\\\/twitter-fullonet-e-la-7\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2007\\\/05\\\/13\\\/twitter-fullonet-e-la-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Twitter, Fullo.net e La 7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Twitter, Fullo.net e La 7 - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/","og_locale":"en_US","og_type":"article","og_title":"Twitter, Fullo.net e La 7 - Fullo","og_description":"Oggi al telegiornale di La7 delle 13.00 si \u00e8 parlato di Twitter, e per descriverne il funzionamento hanno citato il presente blog e le regole che pubblicai tempo addietro e che ultimamente LevySoft ha ridiscusso. Nel proseguimento del post \u00e8 presente la parte del filmato tratta dal TG.","og_url":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/","og_site_name":"Fullo","article_published_time":"2007-05-13T00:01:55+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"Twitter, Fullo.net e La 7","datePublished":"2007-05-13T00:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/"},"wordCount":92,"commentCount":11,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"keywords":["citazioni","discussioni","la7","telegiornale","tg7","twitter"],"articleSection":["lifehack","tecnologia"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/","url":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/","name":"Twitter, Fullo.net e La 7 - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2007-05-13T00:01:55+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2007\/05\/13\/twitter-fullonet-e-la-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Twitter, Fullo.net e La 7"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-Aw","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2032,"url":"https:\/\/www.fullo.net\/blog\/2006\/08\/27\/una-domenica-da-leoni\/","url_meta":{"origin":2264,"position":0},"title":"Una domenica da leoni&#8230;","author":"Francesco Fullone","date":"27\/08\/2006","format":false,"excerpt":"Ho passato sabato e domenica con una maledetta frebbriciattola che mi ha impedito di fare qualsiasi cosa tranne sonnecchiare davanti alla tv... Per passare il tempo (mentre il portatile cercava invano di fare un dist-upgrade da Ubuntu Dapper ad Edgy) avr\u00f2 visto una dozzina di film ed altrettanti OAV dai\u2026","rel":"","context":"In &quot;fumetti&quot;","block_context":{"text":"fumetti","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/fumetti\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2250,"url":"https:\/\/www.fullo.net\/blog\/2007\/04\/16\/svn-auto-update-anche-su-dreamhost\/","url_meta":{"origin":2264,"position":1},"title":"SVN auto update (anche su Dreamhost)","author":"Francesco Fullone","date":"16\/04\/2007","format":false,"excerpt":"Lavorare con SVN offre moltissime comodit\u00e0, dallo sviluppo di gruppo, alla gestione delle revisioni, alla possibilit\u00e0 di fare fork del proprio ramo di sviluppo per gestire pi\u00f9 versioni. Un'ulteriore comodit\u00e0 che ho scoperto da poco \u00e8 la possibilit\u00e0 di attivare dei trigger quando vengono compiute particolari azioni (ad esempio un\u2026","rel":"","context":"In &quot;sysadmin&quot;","block_context":{"text":"sysadmin","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/amministrazione-di-sistema\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2206,"url":"https:\/\/www.fullo.net\/blog\/2007\/02\/05\/php-e-paradox\/","url_meta":{"origin":2264,"position":2},"title":"PHP e Paradox","author":"Francesco Fullone","date":"05\/02\/2007","format":false,"excerpt":"I lavori pi\u00f9 strambi sono anche i pi\u00f9 divertenti, oggi ho recuperato un DB paradox di una decina di anni fa usando PHP, la PECL di Paradox ed una libreria ad hoc per linux. A seguire il piccolo tutorial per accedere ad un db Paradox. Piccola premessa, tutti i test\u2026","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":948,"url":"https:\/\/www.fullo.net\/blog\/2004\/07\/26\/thumbshots\/","url_meta":{"origin":2264,"position":3},"title":"Thumbshots","author":"Francesco Fullone","date":"26\/07\/2004","format":false,"excerpt":"L' Open Thumbshots Project \u00e8 un sito che permette di creare dinamicamente dei thumbnail snapshot (una renderizzazione su bitmap per intenderci) del vostro sito (a patto che questo sia presente su DMOZ), tutto quello che c'\u00e8 da fare \u00e8 copiare il relativo logo nella pagina dove sar\u00e0 presente l'immagini e\u2026","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"Free thumbnail preview by Thumbshots.org","src":"https:\/\/i0.wp.com\/open.thumbshots.org\/attribution.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2279,"url":"https:\/\/www.fullo.net\/blog\/2007\/06\/03\/e-arrivato-ln95-prime-impressioni\/","url_meta":{"origin":2264,"position":4},"title":"E&#8217; arrivato l&#8217;N95, prime impressioni&#8230;","author":"Francesco Fullone","date":"03\/06\/2007","format":false,"excerpt":"E poi dicono che prostrarsi ai piedi delle aziende non serva a nulla... ho ottenuto grazie a Zeno, insieme ad una cricca di blogger pi\u00f9 o meno nota, un N95 fiammante da provare\/testare per un mesetto. Onestamente avrei preferito averlo in omaggio ad vitam, ma per ora non mi lamento\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"Unpaking\/5 - l'agognato N95","src":"https:\/\/i0.wp.com\/farm1.static.flickr.com\/247\/528576766_223f58ed40_m.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2817,"url":"https:\/\/www.fullo.net\/blog\/2011\/08\/19\/hp-cedera-le-linee-di-produzione-dei-pc\/","url_meta":{"origin":2264,"position":5},"title":"HP ceder\u00e0 le linee di produzione dei pc?","author":"Francesco Fullone","date":"19\/08\/2011","format":false,"excerpt":"Come qualcuno di voi avr\u00e0 letto pare che dopo aver risentito della maledizione Palm (notate come tutte le aziende che comprano Palm o prodotti\/marchi di Palm ad un certo punto, a prescindere dalla qualit\u00e0 insita del prodotto, lo dismettano?) HP abbia deciso di non produrre pi\u00f9 hardware sul sistema operativo\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=2264"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2264\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=2264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=2264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=2264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}