{"id":2513,"date":"2008-12-11T23:47:58","date_gmt":"2008-12-11T22:47:58","guid":{"rendered":"https:\/\/www.fullo.net\/blog\/?p=2513"},"modified":"2008-12-11T23:50:54","modified_gmt":"2008-12-11T22:50:54","slug":"movabletype33-vs-wordpress27","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/","title":{"rendered":"MovablePress? WordType?"},"content":{"rendered":"<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/movable-wordpress.gif?resize=450%2C271\" alt=\"movable wordpress, piccola transazione da movabletype 3.3 a wordpress 2.7\" title=\"movable-wordpress\" width=\"450\" height=\"271\" class=\"size-full wp-image-2514\" srcset=\"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/movable-wordpress.gif?w=450&amp;ssl=1 450w, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/movable-wordpress.gif?resize=300%2C180&amp;ssl=1 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/>\n<p>Dopo un po&#8217; di utilizzo di <a href=\"https:\/\/www.fullo.net\/blog\/archives\/2008\/12\/11\/wordpress-27-coltran\/\">WordPress 2.7<\/a>, non ho resistitito e ho iniziato a vagare su internet cercando di ricordare dove avevo gi\u00e0 visto l&#8217;interfaccia con men\u00f9 ad espansione a sinistra. Poi l&#8217;illuminazione, MovableType, e dire che l&#8217;ho usato per anni!<\/p>\n<p>Ringrazio <a href=\"http:\/\/www.simonecarletti.com\/blog\/\">Simone<\/a> per l&#8217;immagine che gli <a href=\"http:\/\/www.rss-world.info\/articoli\/blog\/movable_type_33_parte2.php\">ho grabbato dal sito<\/a> :)<\/p>\n<p>ciauz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo un po&#8217; di utilizzo di WordPress 2.7, non ho resistitito e ho iniziato a vagare su internet cercando di ricordare dove avevo gi\u00e0 visto l&#8217;interfaccia con men\u00f9 ad espansione a sinistra. Poi l&#8217;illuminazione, MovableType, e dire che l&#8217;ho usato per anni! Ringrazio Simone per l&#8217;immagine che gli ho grabbato dal sito :) ciauz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,13,9],"tags":[2033,2032,2034,93,2031,674],"class_list":["post-2513","post","type-post","status-publish","format-standard","hentry","category-cazzate","category-open-source","category-php","tag-movable","tag-movabletype","tag-mt","tag-wordpress","tag-wordpress-27","tag-wp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MovablePress? WordType? - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MovablePress? WordType? - Fullo\" \/>\n<meta property=\"og:description\" content=\"Dopo un po&#8217; di utilizzo di WordPress 2.7, non ho resistitito e ho iniziato a vagare su internet cercando di ricordare dove avevo gi\u00e0 visto l&#8217;interfaccia con men\u00f9 ad espansione a sinistra. Poi l&#8217;illuminazione, MovableType, e dire che l&#8217;ho usato per anni! Ringrazio Simone per l&#8217;immagine che gli ho grabbato dal sito :) ciauz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2008-12-11T22:47:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2008-12-11T22:50:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/movable-wordpress.gif\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"MovablePress? WordType?\",\"datePublished\":\"2008-12-11T22:47:58+00:00\",\"dateModified\":\"2008-12-11T22:50:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/\"},\"wordCount\":66,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/movable-wordpress.gif\",\"keywords\":[\"movable\",\"movabletype\",\"mt\",\"wordpress\",\"wordpress 2.7\",\"wp\"],\"articleSection\":[\"cazzate\",\"open source\",\"php\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/\",\"name\":\"MovablePress? WordType? - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/movable-wordpress.gif\",\"datePublished\":\"2008-12-11T22:47:58+00:00\",\"dateModified\":\"2008-12-11T22:50:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/movable-wordpress.gif\",\"contentUrl\":\"http:\\\/\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/movable-wordpress.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2008\\\/12\\\/11\\\/movabletype33-vs-wordpress27\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MovablePress? WordType?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MovablePress? WordType? - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/","og_locale":"en_US","og_type":"article","og_title":"MovablePress? WordType? - Fullo","og_description":"Dopo un po&#8217; di utilizzo di WordPress 2.7, non ho resistitito e ho iniziato a vagare su internet cercando di ricordare dove avevo gi\u00e0 visto l&#8217;interfaccia con men\u00f9 ad espansione a sinistra. Poi l&#8217;illuminazione, MovableType, e dire che l&#8217;ho usato per anni! Ringrazio Simone per l&#8217;immagine che gli ho grabbato dal sito :) ciauz","og_url":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/","og_site_name":"Fullo","article_published_time":"2008-12-11T22:47:58+00:00","article_modified_time":"2008-12-11T22:50:54+00:00","og_image":[{"url":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/movable-wordpress.gif","type":"","width":"","height":""}],"author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"MovablePress? WordType?","datePublished":"2008-12-11T22:47:58+00:00","dateModified":"2008-12-11T22:50:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/"},"wordCount":66,"commentCount":1,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"image":{"@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/movable-wordpress.gif","keywords":["movable","movabletype","mt","wordpress","wordpress 2.7","wp"],"articleSection":["cazzate","open source","php"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/","url":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/","name":"MovablePress? WordType? - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/#primaryimage"},"image":{"@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/movable-wordpress.gif","datePublished":"2008-12-11T22:47:58+00:00","dateModified":"2008-12-11T22:50:54+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/#primaryimage","url":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/movable-wordpress.gif","contentUrl":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2008\/12\/movable-wordpress.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/movabletype33-vs-wordpress27\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"MovablePress? WordType?"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-Ex","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":631,"url":"https:\/\/www.fullo.net\/blog\/2003\/12\/26\/movabletype\/","url_meta":{"origin":2513,"position":0},"title":"movabletype","author":"Francesco Fullone","date":"26\/12\/2003","format":false,"excerpt":"la notizia \u00e8 passata un po' in sordina, anzi onestamente non ne ha parlato nessuno, ma \u00e8 stata rilasciata la nuova minor release di Movable Type e per la precisione la 2.65: A security issue has been found in Movable Type's XML-RPC server. We suggest that all users of Movable\u2026","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":389,"url":"https:\/\/www.fullo.net\/blog\/2003\/08\/06\/firebird-movable-type\/","url_meta":{"origin":2513,"position":1},"title":"firebird &#038; movable type","author":"Francesco Fullone","date":"06\/08\/2003","format":false,"excerpt":"se usate sia firebird che movabletype vi consiglio di tenere il primo d'occhio.. dalla prossima release potrebbe mostrare qualche interessante plug-in! ciuaz","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":256,"url":"https:\/\/www.fullo.net\/blog\/2003\/05\/12\/rss-for-weblogs\/","url_meta":{"origin":2513,"position":2},"title":"RSS for webLogs","author":"Francesco Fullone","date":"12\/05\/2003","format":false,"excerpt":"gli autori di MovableType hanno avuto l'idea di creare un nuovo RSS specializzato nella trattazione delle notizie dei blog. ciuaz","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2509,"url":"https:\/\/www.fullo.net\/blog\/2008\/12\/11\/wordpress-27-coltran\/","url_meta":{"origin":2513,"position":3},"title":"WordPress 2.7, qualche considerazione per i non sviluppatori","author":"Francesco Fullone","date":"11\/12\/2008","format":false,"excerpt":"Dopo mesi di annunci, alfa, beta, rc \u00e8 finalmente arrivato WordPress 2.7 Coltrane. Questa nuova versione del blog-cms ha visto un notevole lavoro dietro alla nuova interfaccia di backend, lavoro che ha coinvolto decine di sviluppatori, consulenti di usabilit\u00e0 e designer. E che ha portato come risultato finale una dashboard\u2026","rel":"","context":"In &quot;open source&quot;","block_context":{"text":"open source","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/open-source\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2589,"url":"https:\/\/www.fullo.net\/blog\/2009\/03\/02\/scova-il-bug-rel-external-nofollow-e-wordpress-27x\/","url_meta":{"origin":2513,"position":4},"title":"Scova il bug: rel= &#8216;external nofollow e WordPress 2.7.x","author":"Francesco Fullone","date":"02\/03\/2009","format":false,"excerpt":"Ho sbattuto la testa per un paio di giorni prima di capire che il bug riguardante l'errata url associata agli autori dei commenti, che contiene al suo interno la stringa [code] %27%20rel=%27external%20nofollow\/ [\/code] non \u00e8 un problema di WordPress 2.7.x ma di un plugin e nel pi\u00f9 specifico di Google\u2026","rel":"","context":"In &quot;lifehack&quot;","block_context":{"text":"lifehack","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/lifehack\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1720,"url":"https:\/\/www.fullo.net\/blog\/2005\/10\/30\/lavatrice\/","url_meta":{"origin":2513,"position":5},"title":"Lavatrice","author":"Francesco Fullone","date":"30\/10\/2005","format":false,"excerpt":"Oggi ho acquistato la lavatrice, \u00e8 stata un'impresa. Onestamente penso che la scelta (ed il successivo l'acquisto) di un elettrodomestico sia molto pi\u00f9 difficile che quello di uno storage per un datacenter. Ci sono gozzilliardi di modelli ognuno con microscopiche differenze, le stesse case produttrici sembrano sfornarne di nuovi ogni\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=2513"}],"version-history":[{"count":4,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2513\/revisions"}],"predecessor-version":[{"id":2518,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/2513\/revisions\/2518"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=2513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=2513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=2513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}