{"id":276,"date":"2003-06-01T12:28:22","date_gmt":"2003-06-01T10:28:22","guid":{"rendered":"\/\/?p="},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T23:00:00","slug":"firebird","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/","title":{"rendered":"firebird&#8230;"},"content":{"rendered":"<p>ho installato mozilla 1.4rc1 e siccome mi crashava ho deciso di provare <a href=\"http:\/\/texturizer.net\/firebird\/index.html\" title=\"firebird\" target=\"_blank\">firebird<\/a> e devo dire che va VERAMENTE BENEEEEE, gestisce alla grande tutto, l&#8217;altenate CSS chooser, Download, ha i moduli Checky e Leech, il blocco dei pop-up&#8230; e chicca delle chicche <a href=\"http:\/\/www.aggreg8.net\/index.php\" title=\"aggregate\" target=\"_blank\">aggregat8<\/a> un aggregator rss! :D<\/p>\n<p>ciauz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ho installato mozilla 1.4rc1 e siccome mi crashava ho deciso di provare firebird e devo dire che va VERAMENTE BENEEEEE, gestisce alla grande tutto, l&#8217;altenate CSS chooser, Download, ha i moduli Checky e Leech, il blocco dei pop-up&#8230; e chicca delle chicche aggregat8 un aggregator rss! :D ciauz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-276","post","type-post","status-publish","format-standard","hentry","category-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>firebird... - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"firebird... - Fullo\" \/>\n<meta property=\"og:description\" content=\"ho installato mozilla 1.4rc1 e siccome mi crashava ho deciso di provare firebird e devo dire che va VERAMENTE BENEEEEE, gestisce alla grande tutto, l&#8217;altenate CSS chooser, Download, ha i moduli Checky e Leech, il blocco dei pop-up&#8230; e chicca delle chicche aggregat8 un aggregator rss! :D ciauz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2003-06-01T10:28:22+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/firebird\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/firebird\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"firebird&#8230;\",\"datePublished\":\"2003-06-01T10:28:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/firebird\\\/\"},\"wordCount\":50,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"tecnologia\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/firebird\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/firebird\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/firebird\\\/\",\"name\":\"firebird... - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2003-06-01T10:28:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/firebird\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/firebird\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/firebird\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"firebird&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"firebird... - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/","og_locale":"en_US","og_type":"article","og_title":"firebird... - Fullo","og_description":"ho installato mozilla 1.4rc1 e siccome mi crashava ho deciso di provare firebird e devo dire che va VERAMENTE BENEEEEE, gestisce alla grande tutto, l&#8217;altenate CSS chooser, Download, ha i moduli Checky e Leech, il blocco dei pop-up&#8230; e chicca delle chicche aggregat8 un aggregator rss! :D ciauz","og_url":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/","og_site_name":"Fullo","article_published_time":"2003-06-01T10:28:22+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"firebird&#8230;","datePublished":"2003-06-01T10:28:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/"},"wordCount":50,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["tecnologia"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/","url":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/","name":"firebird... - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2003-06-01T10:28:22+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/firebird\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"firebird&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s3OSc1-firebird","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":509,"url":"https:\/\/www.fullo.net\/blog\/2003\/10\/15\/firebird-07\/","url_meta":{"origin":276,"position":0},"title":"firebird 0.7","author":"Francesco Fullone","date":"15\/10\/2003","format":false,"excerpt":"\u00e8 uscito! firebird 0.7 \u00e8 stato rilasciato! e con esso \u00e8 stato rifatto il sito, molto seventies come stile! :) aggiornamento delle 22.07 la homepage \u00e8 tornata alla versione iniziale, pork! manco ho fatto in tempo a fare uno screenshot! ciuaz","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":617,"url":"https:\/\/www.fullo.net\/blog\/2003\/12\/19\/firebird-08\/","url_meta":{"origin":276,"position":1},"title":"firebird 0.8","author":"Francesco Fullone","date":"19\/12\/2003","format":false,"excerpt":"\u00e8 stata rilasciata la pre-release di firebird 0.8! Testate, testate! ciauz","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":690,"url":"https:\/\/www.fullo.net\/blog\/2004\/01\/29\/firebird-08\/","url_meta":{"origin":276,"position":2},"title":"firebird 0.8","author":"Francesco Fullone","date":"29\/01\/2004","format":false,"excerpt":"sta per essere rilasciata la versione 0.8 di firebird, la faccenda si fa interessante... ciauz","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":492,"url":"https:\/\/www.fullo.net\/blog\/2003\/10\/05\/firebird-07\/","url_meta":{"origin":276,"position":3},"title":"firebird 0.7","author":"Francesco Fullone","date":"05\/10\/2003","format":false,"excerpt":"\u00e8 stata rilasciata la RC1 di firebird 0.7! per maggiori info leggete questo post su mozillazine. ciauz","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":528,"url":"https:\/\/www.fullo.net\/blog\/2003\/10\/28\/firebird-071\/","url_meta":{"origin":276,"position":4},"title":"firebird 0.7.1","author":"Francesco Fullone","date":"28\/10\/2003","format":false,"excerpt":"tutti gli utilizzatori di Mac OS X saranno contenti di sapere che \u00e8 stata rilasciata la versione 0.7.1 di firebird. ciuaz","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":389,"url":"https:\/\/www.fullo.net\/blog\/2003\/08\/06\/firebird-movable-type\/","url_meta":{"origin":276,"position":5},"title":"firebird &#038; movable type","author":"Francesco Fullone","date":"06\/08\/2003","format":false,"excerpt":"se usate sia firebird che movabletype vi consiglio di tenere il primo d'occhio.. dalla prossima release potrebbe mostrare qualche interessante plug-in! ciuaz","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/276\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}