{"id":277,"date":"2003-06-01T15:27:15","date_gmt":"2003-06-01T13:27:15","guid":{"rendered":"\/\/?p="},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T23:00:00","slug":"streamripper","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/","title":{"rendered":"streamripper"},"content":{"rendered":"<p>sotto suggerimento <a href=\"http:\/\/jattone.altervista.org\/\" title=\"jatto\" target=\"_blank\">jatto<\/a> ho scaricato <a href=\"http:\/\/streamripper.sourceforge.net\/\" title=\"streamripper\" target=\"_blank\">streamripper<\/a>. Questo simpatico programmillo permette di scaricarsi ed encodarsi al volo in mp3 le varie radio che trasmetto su internet streaming e per semplificare la cosa ne mette a disposizione una nutrita lista ben selezionate ed indicizzate! :D<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>sotto suggerimento jatto ho scaricato streamripper. Questo simpatico programmillo permette di scaricarsi ed encodarsi al volo in mp3 le varie radio che trasmetto su internet streaming e per semplificare la cosa ne mette a disposizione una nutrita lista ben selezionate ed indicizzate! :D ciuaz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-277","post","type-post","status-publish","format-standard","hentry","category-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>streamripper - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"streamripper - Fullo\" \/>\n<meta property=\"og:description\" content=\"sotto suggerimento jatto ho scaricato streamripper. Questo simpatico programmillo permette di scaricarsi ed encodarsi al volo in mp3 le varie radio che trasmetto su internet streaming e per semplificare la cosa ne mette a disposizione una nutrita lista ben selezionate ed indicizzate! :D ciuaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2003-06-01T13:27:15+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/streamripper\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/streamripper\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"streamripper\",\"datePublished\":\"2003-06-01T13:27:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/streamripper\\\/\"},\"wordCount\":45,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"tecnologia\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/streamripper\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/streamripper\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/streamripper\\\/\",\"name\":\"streamripper - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2003-06-01T13:27:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/streamripper\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/streamripper\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/06\\\/01\\\/streamripper\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"streamripper\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"streamripper - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/","og_locale":"en_US","og_type":"article","og_title":"streamripper - Fullo","og_description":"sotto suggerimento jatto ho scaricato streamripper. Questo simpatico programmillo permette di scaricarsi ed encodarsi al volo in mp3 le varie radio che trasmetto su internet streaming e per semplificare la cosa ne mette a disposizione una nutrita lista ben selezionate ed indicizzate! :D ciuaz","og_url":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/","og_site_name":"Fullo","article_published_time":"2003-06-01T13:27:15+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"streamripper","datePublished":"2003-06-01T13:27:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/"},"wordCount":45,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["tecnologia"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/","url":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/","name":"streamripper - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2003-06-01T13:27:15+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2003\/06\/01\/streamripper\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"streamripper"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-4t","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":771,"url":"https:\/\/www.fullo.net\/blog\/2004\/03\/27\/t610-ed-evolution\/","url_meta":{"origin":277,"position":0},"title":"t610 ed evolution","author":"Francesco Fullone","date":"27\/03\/2004","format":false,"excerpt":"ho scritto un mini-tutorial su come sincronizzare i dati presenti nel mio T610 con il groupware client Evolution, adesso il mio cellulare funge da tramite per 3 pc (2 con windows ed outlook ed uno con linux ed evolution)! :D ciuaz","rel":"","context":"In &quot;linux&quot;","block_context":{"text":"linux","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/linux\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":229,"url":"https:\/\/www.fullo.net\/blog\/2003\/05\/03\/ed-ecco-i-risultati\/","url_meta":{"origin":277,"position":1},"title":"&#8230; ed ecco i risultati","author":"Francesco Fullone","date":"03\/05\/2003","format":false,"excerpt":"beh, come volevasi dimostrare... dopo circa 1 ora ho ben 4 scagazzate sul cofano notare che: la macchina \u00e8 stata parcheggiata nel centro di un parcheggio SENZA alberi intorno, fili della luce ed altri possibili appigli per i picciotti (ehm, piccioni)... :x ciuaz","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1993,"url":"https:\/\/www.fullo.net\/blog\/2006\/06\/29\/grown-cube-ed-altri-passatempi\/","url_meta":{"origin":277,"position":2},"title":"Grow Cube ed altri passatempi","author":"Francesco Fullone","date":"29\/06\/2006","format":false,"excerpt":"Ed ecco il passatempo rovina weekend di questa settimana.. L'intera serie Grow di giochini in flash, tempo fa finii la versione RPG in circa un intero pomeriggio.. oggi ho scoperto la versione CUBE... aiuto.. \u00e8 una droooooga.... ciuaz","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1425,"url":"https:\/\/www.fullo.net\/blog\/2005\/05\/30\/php-ed-outlook\/","url_meta":{"origin":277,"position":3},"title":"php ed outlook","author":"Francesco Fullone","date":"30\/05\/2005","format":false,"excerpt":"un connubio possibile, anche se con qualche hack sul registro :) ciuaz","rel":"","context":"In &quot;php&quot;","block_context":{"text":"php","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/php\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":696,"url":"https:\/\/www.fullo.net\/blog\/2004\/02\/03\/usabilit-ed-altro\/","url_meta":{"origin":277,"position":4},"title":"usabilit\u00e0 ed altro&#8230;","author":"Francesco Fullone","date":"03\/02\/2004","format":false,"excerpt":"partendo da uno dei miei referrer mi sono imbattutto in alcuni siti molto interessanti. Il primo di Leandro Agr\u00f2 \u00e8 ricco di spunti ed articoli interessanti sull'usabilit\u00e0, architecto, invece, \u00e8 un blog dedicato all'architettura dell'informazione. Di tutt'altro tipo \u00e8 graphviz, che permette di creare la mappa del prpprio sito in\u2026","rel":"","context":"In &quot;tecnologia&quot;","block_context":{"text":"tecnologia","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":639,"url":"https:\/\/www.fullo.net\/blog\/2003\/12\/28\/un-p-ed-un-po\/","url_meta":{"origin":277,"position":5},"title":"un p\u00f2 ed un po&#8217;","author":"Francesco Fullone","date":"28\/12\/2003","format":false,"excerpt":"Mi \u00e8 stato fatto notare da un bravuomo che commettevo l'errore di scrivere p\u00f2 come forma abbreviata di poco, invece della sua forma corretta po' (con l'apostrofo). Ho corretto gli ultimi post ed il nome della categoria... sperando che non mi ricapiti di inciampare in questo errore un p\u00f2 fastidioso!\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=277"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/277\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}