{"id":367,"date":"2003-07-29T19:44:36","date_gmt":"2003-07-29T17:44:36","guid":{"rendered":"\/\/?p="},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T23:00:00","slug":"maratona","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/","title":{"rendered":"maratona&#8230;"},"content":{"rendered":"<p>ieri alle 18 ero a cesena&#8230;<br \/>\noggi alle 01.30 a cosenza&#8230;.<br \/>\nalle 12.00 a reggio-calabria alle 16.00 di nuovo a cosenza&#8230;<br \/>\ne domani per le 20 spero di essere di nuovo a cesena&#8230;<br \/>\nah ovviamente il tutto in macchina e guidando io&#8230;<br \/>\ne poi mi dicono che ogni tanto sembro un pazzo&#8230;<br \/>\nchiss\u00e0 acosa sar\u00e0 dovuto!<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ieri alle 18 ero a cesena&#8230; oggi alle 01.30 a cosenza&#8230;. alle 12.00 a reggio-calabria alle 16.00 di nuovo a cosenza&#8230; e domani per le 20 spero di essere di nuovo a cesena&#8230; ah ovviamente il tutto in macchina e guidando io&#8230; e poi mi dicono che ogni tanto sembro un pazzo&#8230; chiss\u00e0 acosa sar\u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-367","post","type-post","status-publish","format-standard","hentry","category-pensieri"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>maratona... - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"maratona... - Fullo\" \/>\n<meta property=\"og:description\" content=\"ieri alle 18 ero a cesena&#8230; oggi alle 01.30 a cosenza&#8230;. alle 12.00 a reggio-calabria alle 16.00 di nuovo a cosenza&#8230; e domani per le 20 spero di essere di nuovo a cesena&#8230; ah ovviamente il tutto in macchina e guidando io&#8230; e poi mi dicono che ogni tanto sembro un pazzo&#8230; chiss\u00e0 acosa sar\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2003-07-29T17:44:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/FB_IMG_1515748807284.jpg?fit=1453%2C1453&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"1453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/07\\\/29\\\/maratona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/07\\\/29\\\/maratona\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"maratona&#8230;\",\"datePublished\":\"2003-07-29T17:44:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/07\\\/29\\\/maratona\\\/\"},\"wordCount\":53,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"pensieri\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/07\\\/29\\\/maratona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/07\\\/29\\\/maratona\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/07\\\/29\\\/maratona\\\/\",\"name\":\"maratona... - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2003-07-29T17:44:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/07\\\/29\\\/maratona\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/07\\\/29\\\/maratona\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2003\\\/07\\\/29\\\/maratona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"maratona&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"maratona... - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/","og_locale":"it_IT","og_type":"article","og_title":"maratona... - Fullo","og_description":"ieri alle 18 ero a cesena&#8230; oggi alle 01.30 a cosenza&#8230;. alle 12.00 a reggio-calabria alle 16.00 di nuovo a cosenza&#8230; e domani per le 20 spero di essere di nuovo a cesena&#8230; ah ovviamente il tutto in macchina e guidando io&#8230; e poi mi dicono che ogni tanto sembro un pazzo&#8230; chiss\u00e0 acosa sar\u00e0 [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/","og_site_name":"Fullo","article_published_time":"2003-07-29T17:44:36+00:00","og_image":[{"width":1453,"height":1453,"url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2021\/05\/FB_IMG_1515748807284.jpg?fit=1453%2C1453&ssl=1","type":"image\/jpeg"}],"author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Scritto da":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"maratona&#8230;","datePublished":"2003-07-29T17:44:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/"},"wordCount":53,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["pensieri"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/","url":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/","name":"maratona... - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2003-07-29T17:44:36+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2003\/07\/29\/maratona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"maratona&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s3OSc1-maratona","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2975,"url":"https:\/\/www.fullo.net\/blog\/2012\/03\/19\/facciamo-un-tech-hub-a-cesena\/","url_meta":{"origin":367,"position":0},"title":"Facciamo un tech-hub a Cesena?","author":"Francesco Fullone","date":"19\/03\/2012","format":false,"excerpt":"L'idea \u00e8 venuta fuori un po' cos\u00ec per scherzo durante una sessione di release planning (e mentoring) con una startup: \"Perch\u00e8 non creiamo un cowo dove ospitare le proto-startup e le startup che di volta in volta ci vengono a chiedere supporto nel metodo e nella tecnologia?\". Dopo 30 minuti\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2075,"url":"https:\/\/www.fullo.net\/blog\/2006\/10\/09\/securityday-a-cesena\/","url_meta":{"origin":367,"position":1},"title":"SecurityDay a Cesena","author":"Francesco Fullone","date":"09\/10\/2006","format":false,"excerpt":"Ho finalmente deciso il titolo (ma soprattutto l'argomento) del talk che terr\u00f2 durante il prossimo SecurityDay\/LinuxDay a Cesena. Il talk in questione si intitoler\u00e0 quindi \"Dal tuo sito al mio spam relay, piccole regole di hardening per siti in php\" e continuer\u00e0 il discorso lasciato aperto lo scorso anno, e\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2442,"url":"https:\/\/www.fullo.net\/blog\/2008\/07\/17\/blogdinner-romagna-summer-season\/","url_meta":{"origin":367,"position":2},"title":"blogDinner roMagna summer season #2","author":"Francesco Fullone","date":"17\/07\/2008","format":false,"excerpt":"Ecco quindi le ultime informazioni per il blogDinner roMagna: \u201cOstaria del Mare\u201d Via Casette, 5 - Montaletto di Cervia (RA) tel. 0544 965617 - chiuso luned\u00ec Per chi viene da Nord (faenza\/bologna) o da Sud (cattolina\/rimini) il luogo di appuntamento \u00e8 davanti casello di Cesena Sud (mi fanno presente che\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2100,"url":"https:\/\/www.fullo.net\/blog\/2006\/10\/28\/securityday-e-linuxday-missione-compiuta\/","url_meta":{"origin":367,"position":3},"title":"SecurityDay e LinuxDay, missione compiuta.","author":"Francesco Fullone","date":"28\/10\/2006","format":false,"excerpt":"Finalmente sono finite le due giornate dedicate ai talk sulla sicurezza e l'opensource tenutesi a Cesena. Come ogni hanno l'affluenza dall'esterno \u00e8 stata positiva, meno positiva quella degli studenti di scienze dell'informazione che, a parte rare eccezioni, hanno preferito continuare a giocare al biliardo di yahoo! in laboratorio. Le considerazioni\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"Security day a cesena","src":"https:\/\/i0.wp.com\/static.flickr.com\/88\/280422656_c38e38a221_t.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2288,"url":"https:\/\/www.fullo.net\/blog\/2007\/06\/18\/blogdinner-romagna-5\/","url_meta":{"origin":367,"position":4},"title":"BlogDinner roMagna","author":"Francesco Fullone","date":"18\/06\/2007","format":false,"excerpt":"Me ne aveva riparlato Daniele, poi per\u00f2, come al solito, ce ne siamo dimenticati bellamente ed \u00e8 passato qualche mese... beh.. Siccome a Luglio non si pu\u00f2 non andare a cesenatico a mangiare il pesce (o le alghe se si \u00e8 vegetariani) direi che la prossima blogDinner roMagnola (la quarta\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2287,"url":"https:\/\/www.fullo.net\/blog\/2007\/06\/18\/si-laurea-santana\/","url_meta":{"origin":367,"position":5},"title":"Si laurea &#8220;Santana&#8221;, chiamata alle armi","author":"Francesco Fullone","date":"18\/06\/2007","format":false,"excerpt":"Gioved\u00ec si laurea Francesco \"Santana\" Sordillo, la proclamazione si terr\u00e0 a Cesena all'interno del corso di laurea di Scienze dell'Informazione. Adesso, se per tale data non avete nulla da fare e, se volete sfogare i vostri bassi istinti verso un povero disgraziato, la cui unica colpa \u00e8 stata quella di\u2026","rel":"","context":"In &quot;cazzate&quot;","block_context":{"text":"cazzate","link":"https:\/\/www.fullo.net\/blog\/category\/cazzate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=367"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/367\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}