{"id":644,"date":"2004-01-03T23:05:09","date_gmt":"2004-01-03T21:05:09","guid":{"rendered":"\/\/?p="},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T23:00:00","slug":"parte-il-cineforum-sprite","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/","title":{"rendered":"parte il cineforum S.P.R.I.Te."},"content":{"rendered":"<p>tra una settima parte la terza edizione del <a href=\"http:\/\/sprite.csr.unibo.it\/cineforum03\/\">cineforum<\/a> di S.P.R.I.Te., l&#8217;associazione studentesca dove militavo (e che continuer\u00f2 a bazzicare.. pensate di esservi liberati di me? eh?!).<br \/>\nQuindi se \u00e8 luned\u00ec sera, abitate nei pressi di Cesena, e non sapete che fare.. fate un salto! E&#8217; gratis e vi offriamo anche la birra! :)<\/p>\n<p>ciuaz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>tra una settima parte la terza edizione del cineforum di S.P.R.I.Te., l&#8217;associazione studentesca dove militavo (e che continuer\u00f2 a bazzicare.. pensate di esservi liberati di me? eh?!). Quindi se \u00e8 luned\u00ec sera, abitate nei pressi di Cesena, e non sapete che fare.. fate un salto! E&#8217; gratis e vi offriamo anche la birra! :) ciuaz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-644","post","type-post","status-publish","format-standard","hentry","category-sdi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>parte il cineforum S.P.R.I.Te. - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"parte il cineforum S.P.R.I.Te. - Fullo\" \/>\n<meta property=\"og:description\" content=\"tra una settima parte la terza edizione del cineforum di S.P.R.I.Te., l&#8217;associazione studentesca dove militavo (e che continuer\u00f2 a bazzicare.. pensate di esservi liberati di me? eh?!). Quindi se \u00e8 luned\u00ec sera, abitate nei pressi di Cesena, e non sapete che fare.. fate un salto! E&#8217; gratis e vi offriamo anche la birra! :) ciuaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2004-01-03T21:05:09+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2004\\\/01\\\/03\\\/parte-il-cineforum-sprite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2004\\\/01\\\/03\\\/parte-il-cineforum-sprite\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"parte il cineforum S.P.R.I.Te.\",\"datePublished\":\"2004-01-03T21:05:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2004\\\/01\\\/03\\\/parte-il-cineforum-sprite\\\/\"},\"wordCount\":66,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"SdI\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2004\\\/01\\\/03\\\/parte-il-cineforum-sprite\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2004\\\/01\\\/03\\\/parte-il-cineforum-sprite\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2004\\\/01\\\/03\\\/parte-il-cineforum-sprite\\\/\",\"name\":\"parte il cineforum S.P.R.I.Te. - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2004-01-03T21:05:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2004\\\/01\\\/03\\\/parte-il-cineforum-sprite\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2004\\\/01\\\/03\\\/parte-il-cineforum-sprite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2004\\\/01\\\/03\\\/parte-il-cineforum-sprite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"parte il cineforum S.P.R.I.Te.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"parte il cineforum S.P.R.I.Te. - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/","og_locale":"en_US","og_type":"article","og_title":"parte il cineforum S.P.R.I.Te. - Fullo","og_description":"tra una settima parte la terza edizione del cineforum di S.P.R.I.Te., l&#8217;associazione studentesca dove militavo (e che continuer\u00f2 a bazzicare.. pensate di esservi liberati di me? eh?!). Quindi se \u00e8 luned\u00ec sera, abitate nei pressi di Cesena, e non sapete che fare.. fate un salto! E&#8217; gratis e vi offriamo anche la birra! :) ciuaz","og_url":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/","og_site_name":"Fullo","article_published_time":"2004-01-03T21:05:09+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"parte il cineforum S.P.R.I.Te.","datePublished":"2004-01-03T21:05:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/"},"wordCount":66,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["SdI"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/","url":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/","name":"parte il cineforum S.P.R.I.Te. - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2004-01-03T21:05:09+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2004\/01\/03\/parte-il-cineforum-sprite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"parte il cineforum S.P.R.I.Te."}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-ao","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1060,"url":"https:\/\/www.fullo.net\/blog\/2004\/10\/18\/riparte-il-cineforum-sprite\/","url_meta":{"origin":644,"position":0},"title":"riparte il cineforum S.P.R.I.Te.","author":"Francesco Fullone","date":"18\/10\/2004","format":false,"excerpt":"Anche quest'anno la S.P.R.I.Te. ha organizzato il Cineforum, ed essendo non pi\u00f9 ufficialmente attivista dell'associazione mi sono limitato ad aiutare a curare la scaletta e la scelta dei film ;) Anche quest anno ci siamo proposti di organizzare il Cineforum, giunto alla sua quarta edizione. E anche quest' anno il\u2026","rel":"","context":"In &quot;SdI&quot;","block_context":{"text":"SdI","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/sdi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1794,"url":"https:\/\/www.fullo.net\/blog\/2005\/12\/01\/spriteblogs\/","url_meta":{"origin":644,"position":1},"title":"SpriteBlogs!","author":"Francesco Fullone","date":"01\/12\/2005","format":false,"excerpt":"Dopo il Linuxday \u00e8 impazzata la moda del blog anche in S.P.R.I.Te. (finalmente) ed ecco che alla famiglia dei blog Spriters si aggiungono nuovi diari. A questo punto i blog sono, in ordine di apparizione sul web: Full(o)bloG (e che me linko a f\u00e0?) S.P.R.I.Te. Koolinus Cphp Sigi Cippa Falluccox\u2026","rel":"","context":"In &quot;SdI&quot;","block_context":{"text":"SdI","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/sdi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":42,"url":"https:\/\/www.fullo.net\/blog\/2002\/11\/23\/fullo-new-phpconfsdi\/","url_meta":{"origin":644,"position":2},"title":"$fullo = new PHP_Conf(&#8216;sdi&#8217;);","author":"Francesco Fullone","date":"23\/11\/2002","format":false,"excerpt":"Ho fatto la mia prima conferenza! :D Devo dire che, a parte un primo momento di panico, ed i lucidi finiti 10 minuti prima di iniziare, mi sono comportato benino! ;P Presto pubblichero' i miei lucidi (... spudoratamente tratti da quelli di Jes\u00fas Castagnetto ) qui e sul sito della\u2026","rel":"","context":"In &quot;SdI&quot;","block_context":{"text":"SdI","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/sdi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2100,"url":"https:\/\/www.fullo.net\/blog\/2006\/10\/28\/securityday-e-linuxday-missione-compiuta\/","url_meta":{"origin":644,"position":3},"title":"SecurityDay e LinuxDay, missione compiuta.","author":"Francesco Fullone","date":"28\/10\/2006","format":false,"excerpt":"Finalmente sono finite le due giornate dedicate ai talk sulla sicurezza e l'opensource tenutesi a Cesena. Come ogni hanno l'affluenza dall'esterno \u00e8 stata positiva, meno positiva quella degli studenti di scienze dell'informazione che, a parte rare eccezioni, hanno preferito continuare a giocare al biliardo di yahoo! in laboratorio. Le considerazioni\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.fullo.net\/blog\/category\/eventi\/"},"img":{"alt_text":"Security day a cesena","src":"https:\/\/i0.wp.com\/static.flickr.com\/88\/280422656_c38e38a221_t.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2140,"url":"https:\/\/www.fullo.net\/blog\/2006\/12\/05\/fai-del-tuo-peggio\/","url_meta":{"origin":644,"position":4},"title":"Fai del tuo peggio","author":"Francesco Fullone","date":"05\/12\/2006","format":false,"excerpt":"Samuele Silva, che non linko apposta, ha minacciato la blogsfera di mostrare le peggiori foto fatte durante il BarCamp. Pensa di impaurirmi con questa semplice foto (che linko in quanto su flickr). Beh, fai del tuo peggio.. ma non riuscirai mai a raggiungere quello che quei disgraziati dei miei amichetti\u2026","rel":"","context":"In &quot;foto&quot;","block_context":{"text":"foto","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/foto\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":81,"url":"https:\/\/www.fullo.net\/blog\/2003\/01\/12\/morto-il-server-viva-il-server\/","url_meta":{"origin":644,"position":5},"title":"\u00e8 morto il server! viva il server","author":"Francesco Fullone","date":"12\/01\/2003","format":false,"excerpt":"Purtroppo mercoled\u00ec scorso il mio bellissimo pc ha deciso di abbandonarmi, anzi per essere pi\u00f9 precisi la scheda madre ha deciso che era stanca di lavorare 24h al giorno, 7g la settimana. E quindi mi sono ritrovato senza un server a casa con cui poter lavorare... :( Purtroppo non avendo\u2026","rel":"","context":"In &quot;di tutto un po'&quot;","block_context":{"text":"di tutto un po'","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=644"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/644\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}