{"id":9,"date":"2002-10-20T21:32:09","date_gmt":"2002-10-20T19:32:09","guid":{"rendered":"\/\/?p="},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T23:00:00","slug":"se-sei-della-siae-non-leggi","status":"publish","type":"post","link":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/","title":{"rendered":"se sei della SIAE non leggi"},"content":{"rendered":"<p>Ultimamente leggendo un <a href=\"http:\/\/www.theregus.com\/content\/4\/26656.html\" target=\"_BLANK\">articolo<\/a> riguardante la nuova politica<br \/>\ndi rilascio patch della Red-Hat mi \u00e8 venuta una sfolgorante idea,<br \/>\nperch\u00e8 non applicare lo stesso concetto alla SIAE?<\/p>\n<p>si potrebbero quindi rilasciare documenti\/software\/musica con il <br \/>\nfamoso <i>copyLeft<\/i> ma aggiungendo in fondo la postilla:<\/p>\n<blockquote><p>Se lavori per la SIAE o ne appoggi la causa non puoi : <br \/>\nascoltare, riprodurre, leggere e utilizzare, il seguente prodotto.<br \/>\nPena pagamento di XXXX euro all&#8217;autore ed alla Free Software Fondation etc etc&#8230;<\/p><\/blockquote>\n<p>\nmmh non male come idea, potrei brevettarla ;P.<\/p>\n<p>ciuaz <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ultimamente leggendo un articolo riguardante la nuova politica di rilascio patch della Red-Hat mi \u00e8 venuta una sfolgorante idea, perch\u00e8 non applicare lo stesso concetto alla SIAE? si potrebbero quindi rilasciare documenti\/software\/musica con il famoso copyLeft ma aggiungendo in fondo la postilla: Se lavori per la SIAE o ne appoggi la causa non puoi : [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-9","post","type-post","status-publish","format-standard","hentry","category-pensieri"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>se sei della SIAE non leggi - Fullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"se sei della SIAE non leggi - Fullo\" \/>\n<meta property=\"og:description\" content=\"Ultimamente leggendo un articolo riguardante la nuova politica di rilascio patch della Red-Hat mi \u00e8 venuta una sfolgorante idea, perch\u00e8 non applicare lo stesso concetto alla SIAE? si potrebbero quindi rilasciare documenti\/software\/musica con il famoso copyLeft ma aggiungendo in fondo la postilla: Se lavori per la SIAE o ne appoggi la causa non puoi : [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/\" \/>\n<meta property=\"og:site_name\" content=\"Fullo\" \/>\n<meta property=\"article:published_time\" content=\"2002-10-20T19:32:09+00:00\" \/>\n<meta name=\"author\" content=\"Francesco Fullone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fullo\" \/>\n<meta name=\"twitter:site\" content=\"@fullo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Fullone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/20\\\/se-sei-della-siae-non-leggi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/20\\\/se-sei-della-siae-non-leggi\\\/\"},\"author\":{\"name\":\"Francesco Fullone\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"headline\":\"se sei della SIAE non leggi\",\"datePublished\":\"2002-10-20T19:32:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/20\\\/se-sei-della-siae-non-leggi\\\/\"},\"wordCount\":92,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"articleSection\":[\"pensieri\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/20\\\/se-sei-della-siae-non-leggi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/20\\\/se-sei-della-siae-non-leggi\\\/\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/20\\\/se-sei-della-siae-non-leggi\\\/\",\"name\":\"se sei della SIAE non leggi - Fullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\"},\"datePublished\":\"2002-10-20T19:32:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/20\\\/se-sei-della-siae-non-leggi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/20\\\/se-sei-della-siae-non-leggi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/2002\\\/10\\\/20\\\/se-sei-della-siae-non-leggi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"se sei della SIAE non leggi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/\",\"name\":\"Fullo\",\"description\":\"nulla e&#039; impossibile per chi non lo deve fare!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/#\\\/schema\\\/person\\\/24e91bc6caea6c411a8668df5639428c\",\"name\":\"Francesco Fullone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Francesco Fullone\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.fullo.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.fullo.net\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fullo\",\"https:\\\/\\\/x.com\\\/fullo\"],\"url\":\"https:\\\/\\\/www.fullo.net\\\/blog\\\/author\\\/fullo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"se sei della SIAE non leggi - Fullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/","og_locale":"en_US","og_type":"article","og_title":"se sei della SIAE non leggi - Fullo","og_description":"Ultimamente leggendo un articolo riguardante la nuova politica di rilascio patch della Red-Hat mi \u00e8 venuta una sfolgorante idea, perch\u00e8 non applicare lo stesso concetto alla SIAE? si potrebbero quindi rilasciare documenti\/software\/musica con il famoso copyLeft ma aggiungendo in fondo la postilla: Se lavori per la SIAE o ne appoggi la causa non puoi : [&hellip;]","og_url":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/","og_site_name":"Fullo","article_published_time":"2002-10-20T19:32:09+00:00","author":"Francesco Fullone","twitter_card":"summary_large_image","twitter_creator":"@fullo","twitter_site":"@fullo","twitter_misc":{"Written by":"Francesco Fullone"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/#article","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/"},"author":{"name":"Francesco Fullone","@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"headline":"se sei della SIAE non leggi","datePublished":"2002-10-20T19:32:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/"},"wordCount":92,"commentCount":0,"publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"articleSection":["pensieri"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/","url":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/","name":"se sei della SIAE non leggi - Fullo","isPartOf":{"@id":"https:\/\/www.fullo.net\/blog\/#website"},"datePublished":"2002-10-20T19:32:09+00:00","breadcrumb":{"@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fullo.net\/blog\/2002\/10\/20\/se-sei-della-siae-non-leggi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fullo.net\/blog\/"},{"@type":"ListItem","position":2,"name":"se sei della SIAE non leggi"}]},{"@type":"WebSite","@id":"https:\/\/www.fullo.net\/blog\/#website","url":"https:\/\/www.fullo.net\/blog\/","name":"Fullo","description":"nulla e&#039; impossibile per chi non lo deve fare!","publisher":{"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fullo.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.fullo.net\/blog\/#\/schema\/person\/24e91bc6caea6c411a8668df5639428c","name":"Francesco Fullone","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","url":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Francesco Fullone"},"logo":{"@id":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/10\/hawiaina-gold-circled-white.png?fit=622%2C622&ssl=1"},"sameAs":["http:\/\/www.fullo.net","https:\/\/www.linkedin.com\/in\/fullo","https:\/\/x.com\/fullo"],"url":"https:\/\/www.fullo.net\/blog\/author\/fullo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3OSc1-9","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":22,"url":"https:\/\/www.fullo.net\/blog\/2002\/10\/24\/classifichiamo-gli-informatici-le-specie\/","url_meta":{"origin":9,"position":0},"title":"Classifichiamo gli informatici: Le specie","author":"Francesco Fullone","date":"24\/10\/2002","format":false,"excerpt":"disclaimer: sto scrivendo tutto questo sotto un possente mal di testa causato da una sbronza presa 2 giorni fa (!). Le mie elucubrazioni si basano su fatti veri e comunque descrivono l'aspetto medio della vita da informatico, considerate una buona varianza quindi, se in qualche modo offender\u00f2 il vostro essere\u2026","rel":"","context":"In &quot;lifehack&quot;","block_context":{"text":"lifehack","link":"https:\/\/www.fullo.net\/blog\/category\/di-tutto-un-po\/lifehack\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4027,"url":"https:\/\/www.fullo.net\/blog\/2023\/06\/25\/sostenibilita-del-software-ovvero-andare-oltre-al-solo-green-software\/","url_meta":{"origin":9,"position":1},"title":"Sostenibilit\u00e0 del Software, ovvero: andare oltre al solo Green Software","author":"Francesco Fullone","date":"25\/06\/2023","format":false,"excerpt":"Dobbiamo capire che la sostenibilit\u00e0 del software va oltre le best practices della Green Software Foundation relative al Green IT.","rel":"","context":"In &quot;business design&quot;","block_context":{"text":"business design","link":"https:\/\/www.fullo.net\/blog\/category\/entrepreneurship\/business-design\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2023\/06\/1685968227492.gif?fit=1136%2C620&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2023\/06\/1685968227492.gif?fit=1136%2C620&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2023\/06\/1685968227492.gif?fit=1136%2C620&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2023\/06\/1685968227492.gif?fit=1136%2C620&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2023\/06\/1685968227492.gif?fit=1136%2C620&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":841,"url":"https:\/\/www.fullo.net\/blog\/2004\/05\/12\/fatta-la-legge-stupida\/","url_meta":{"origin":9,"position":2},"title":"fatta la legge (stupida)&#8230;","author":"Francesco Fullone","date":"12\/05\/2004","format":false,"excerpt":"ho trovato su manteblog un interessante stralcio della legge 106\/2004 che mi ha fatto capire quanto inizi a fare eccessivamente schifo (ma soprattutto quanto sia STUPIDO) l'attuale governo italiano, ovviamente seguito a ruota dal parlamento europeo per il discorso della brevettibilit\u00e0 del software. a questo punto il mio suggerimento \u00e8\u2026","rel":"","context":"In &quot;pensieri&quot;","block_context":{"text":"pensieri","link":"https:\/\/www.fullo.net\/blog\/category\/pensieri\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3340,"url":"https:\/\/www.fullo.net\/blog\/2016\/06\/09\/continuous-budgeting\/","url_meta":{"origin":9,"position":3},"title":"Continuous Budgeting","author":"Francesco Fullone","date":"09\/06\/2016","format":false,"excerpt":"Dalla mia prima esperienza imprenditoriale e fino ad ideato, la compilazione del budget \u00e8 stata un\u2019attivit\u00e0 formativa e ricca di discussioni che mi ha portato a riflettere su molti aspetti del futuro lavoro dandomi una consapevolezza importante sul nostro mondo. Anche se, non nascondo, che per i primi anni abbia\u2026","rel":"","context":"In &quot;Entrepreneurship&quot;","block_context":{"text":"Entrepreneurship","link":"https:\/\/www.fullo.net\/blog\/category\/entrepreneurship\/"},"img":{"alt_text":"beyond and continuous budgeting","src":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2020\/02\/maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2020\/02\/maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2020\/02\/maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2020\/02\/maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.fullo.net\/blog\/wp-content\/uploads\/2020\/02\/maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4179,"url":"https:\/\/www.fullo.net\/blog\/2024\/03\/01\/la-sostenibilita-digitale-e-un-vantaggio-competitivo\/","url_meta":{"origin":9,"position":4},"title":"La sostenibilit\u00e0 digitale \u00e8 un vantaggio competitivo","author":"Francesco Fullone","date":"01\/03\/2024","format":false,"excerpt":"La sostenibilit\u00e0 digitale \u00e8, in fondo, un vantaggio competitivo che le aiuter\u00e0 a gestire al meglio il futuro.","rel":"","context":"In &quot;Entrepreneurship&quot;","block_context":{"text":"Entrepreneurship","link":"https:\/\/www.fullo.net\/blog\/category\/entrepreneurship\/"},"img":{"alt_text":"What people think building a sustainable internet involves vs what it might actually be","src":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/03\/pdzh2986.bmp","width":350,"height":200,"srcset":"https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/03\/pdzh2986.bmp 1x, https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/03\/pdzh2986.bmp 1.5x, https:\/\/www.fullo.net\/blog\/wp-content\/uploads\/2024\/03\/pdzh2986.bmp 2x"},"classes":[]},{"id":1699,"url":"https:\/\/www.fullo.net\/blog\/2005\/10\/17\/vota-contro-i-brevetti-software\/","url_meta":{"origin":9,"position":5},"title":"Vota contro i brevetti software","author":"Francesco Fullone","date":"17\/10\/2005","format":false,"excerpt":"I brevetti software rappresentano un intralcio all'innovazione e una minaccia ingiusta agli sviluppatori e agli utenti del software. Il 6 luglio, il Parlamento Europeo fortunatamente respinse una proposta per una direttiva sui brevetti software, pero' la lotta va avanti. Oggi abbiamo un'opportunita' di primo livello per far s\u00ec che leader\u2026","rel":"","context":"In &quot;open source&quot;","block_context":{"text":"open source","link":"https:\/\/www.fullo.net\/blog\/category\/tecnologia\/open-source\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":0,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/posts\/9\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/media?parent=9"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/categories?post=9"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fullo.net\/blog\/wp-json\/wp\/v2\/tags?post=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}